{"id":2240,"date":"2025-09-17T23:23:43","date_gmt":"2025-09-17T21:23:43","guid":{"rendered":"https:\/\/k-ny.art\/serie-cerrada-irony-edge\/"},"modified":"2026-07-05T11:09:36","modified_gmt":"2026-07-05T09:09:36","slug":"serie-cerrada-irony-edge","status":"publish","type":"page","link":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/","title":{"rendered":"Cluster-IRONY- EDGE"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbWork\u00bb _builder_version=\u00bb4.27.6&#8243; background_enable_image=\u00bboff\u00bb background_size=\u00bbinitial\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb1370.6px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row custom_padding_last_edited=\u00bboff|phone\u00bb _builder_version=\u00bb4.16&#8243; background_position=\u00bbbottom_center\u00bb custom_padding_tablet=\u00bb17vw||17vw||false\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb|500|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb56px\u00bb header_2_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bbrgba(0,0,0,0.35)\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb2em\u00bb transform_translate_linked=\u00bboff\u00bb max_width=\u00bb700px\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb module_alignment=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb26px\u00bb header_2_font_size_last_edited=\u00bbon|tablet\u00bb header_3_font_size_phone=\u00bb10px\u00bb header_3_font_size_last_edited=\u00bboff|desktop\u00bb module_alignment_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\">CLUSTER<\/p>\n<h2>IRONY &#038; EDGE<\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,3_5,1_5&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/05\/IRONY-EDGE-\u2014-K-NY-Cluster-Icon.jpg\u00bb alt=\u00bbFragmented luminous ring representing the K-NY cluster IRONY &amp; EDGE \u2014 instability, disruption, conceptual irony, and controlled imperfection within the K-NY system.\u00bb title_text=\u00bbIRONY &amp; EDGE \u2014 K-NY Cluster Icon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/CC.png\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb60%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: right;\"><b><\/b><\/h2>\n<h2 style=\"text-align: right;\"><b><\/b><\/h2>\n<h3>IRONY &#038; EDGE &#8211; Truth glitches. Irony cuts. <\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La verdad titubea.<br \/>La iron\u00eda corta.<\/p>\n<p>IRONY &#038; EDGE es un cluster cerrado compuesto por cinco obras.<\/p>\n<p>Dentro del sistema K-NY, explora la relaci\u00f3n entre percepci\u00f3n, distancia y claridad.<\/p>\n<p>Impulso \u2192 Expansi\u00f3n \u2192 Consciencia \u2192 Umbral \u2192 Estado<\/p>\n<p>La distancia se convierte en perspectiva.<br \/>La perspectiva se convierte en claridad.<br \/>La claridad se convierte en libertad.<\/p>\n<p>Un cl\u00faster completo permanece cerrado.<br \/>Disponibilidad y condiciones individuales bajo solicitud.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/07\/K-NY-Gallery-Space.3-1.png\u00bb title_text=\u00bbK-NY Gallery Space.\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb alt=\u00bbK-NY artwork in the K-NY Gallery Space, demonstrating the relationship between artwork, architecture and perception.\u00bb sticky_enabled=\u00bb0&#8243; url=\u00bbhttps:\/\/k-ny.art\/es\/error-404\/\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.7&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb54px||||false|false\u00bb hover_enabled=\u00bb0&#8243; text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>Error 404:<br \/>Truth Not Found<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>IRONY &#038; EDGE<br \/>(Work No. 1 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg\u00bb alt=\u00bbK-NY Vault icon \u2013 curated access to unseen artworks\u00bb title_text=\u00bbK-NY Vault icon\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; url=\u00bbhttps:\/\/k-ny.art\/es\/the-vault\/\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb73px||||false|false\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\"><strong>NO BRAIN, NO FUN<\/strong><br \/>Masterpiece II \/ 2026<\/p>\n<p style=\"text-align: left;\">[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/12\/K-NY-Safe-no-brain-no-fun.jpg\u00bb alt=\u00bbK-NY Private Release safe icon \u2013 curated access to private unreleased artworks\u00bb title_text=\u00bbK-NY Private Release safe icon\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243; url=\u00bbhttps:\/\/k-ny.art\/es\/the-vault\/\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.7&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb48px||||false|false\u00bb hover_enabled=\u00bb0&#8243; text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>ART OR WHAT?<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>IRONY &#038; EDGE<br \/>(Work No. 3 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>PRIVATE RELEASE<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg\u00bb alt=\u00bbK-NY Vault icon \u2013 curated access to unseen artworks\u00bb title_text=\u00bbK-NY Vault icon\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/the-vault\/\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb48px||||false|false\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>IREM LOPSUM<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>IRONY &#038; EDGE<br \/>(Work No. 4 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg\u00bb alt=\u00bbK-NY Vault icon \u2013 curated access to unseen artworks\u00bb title_text=\u00bbK-NY Vault icon\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/the-vault\/\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb custom_padding=\u00bb48px||||false|false\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>MINUTE 7<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>IRONY &#038; EDGE<br \/>(Work No. 5 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>LECTURA CURATORIAL DEL CLUSTER<\/p>\n<p>IRONY &#038; EDGE describe el movimiento de la perturbaci\u00f3n hacia la claridad.<br \/>Las obras investigan la iron\u00eda no como recurso estil\u00edstico, sino como una forma de percepci\u00f3n \u2014 lo bastante precisa para hacer visibles los sistemas sin someterse a ellos. Entre tensi\u00f3n, autorreflexi\u00f3n e inestabilidad controlada surge un estado de soberan\u00eda intelectual. Este cluster no se define por la provocaci\u00f3n, sino por la capacidad de transformar la distancia en precisi\u00f3n.  <\/p>\n<p>POSICI\u00d3N DENTRO DEL SISTEMA K-NY<\/p>\n<p>Dentro del sistema K-NY, IRONY &#038; EDGE marca el momento en que la percepci\u00f3n empieza a tomar conciencia de s\u00ed misma. Mientras FOCUS &#038; STRENGTH establece el origen y POWER &#038; FREEDOM formula la autoautoridad, este cluster describe la independencia cultural e intelectual del sistema. No como cr\u00edtica. Sino como una forma de claridad.   <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>The K-NY Collection<\/p>\n<p>Una obra publicada representa la identidad visible de su cluster. Encierra la actitud, la visi\u00f3n y el lujo rebelde de K-NY \u2014 donde la propia presencia se convierte en una forma de arte. Cada pieza est\u00e1 destinada a ser vista y, aun as\u00ed, permanece singular \u2014 creada para quienes comprenden la diferencia entre visibilidad y sustancia.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>IRONY &#038; EDGE<span class=\"Apple-converted-space\"> <\/span><\/h3>\n<p>La percepci\u00f3n abre espacios emocionales.<br \/>La risa abre todos los dem\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/07\/Smartist_5F7FF275-9E48-4CB5-ABFF-40B7D9EA71B4-scaled.jpg\u00bb alt=\u00bbK-NY artwork in the K-NY Gallery Space, demonstrating the relationship between artwork, architecture and perception.\u00bb title_text=\u00bbK-NY Gallery Space.\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/break-free\/\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_cta button_url=\u00bbhttps:\/\/k-ny.art\/es\/error-404\/\u00bb button_text=\u00bbM\u00e1s detalles\u00bb _builder_version=\u00bb4.27.6&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbrgba(0,0,0,0)\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 90%|#000000 100%\u00bb button_bg_color_gradient_start=\u00bb#ffffff\u00bb button_bg_color_gradient_start_position=\u00bb90%\u00bb button_bg_color_gradient_end=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb button_custom_padding=\u00bb|0px||0px||true\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb-120px|40px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb|-40px||80px|false|false\u00bb custom_margin_tablet=\u00bb||-60px|\u00bb custom_margin_last_edited=\u00bboff|tablet\u00bb custom_padding=\u00bb|1px|25px||false|false\u00bb link_option_url=\u00bbhttps:\/\/k-ny.art\/es\/error-404\/\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_horizontal=\u00bb-70px\u00bb box_shadow_vertical=\u00bb70px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.1)\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb0px\u00bb box_shadow_vertical_button=\u00bb1px\u00bb box_shadow_blur_button=\u00bb0px\u00bb box_shadow_color_button=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>ARTWORK<\/p>\n<h2>ERROR 404: TRUTH NOT FOUND<\/h2>\n<p><b><\/b><\/p>\n<p><b><\/b><\/p>\n<p><strong>\u00ab La verdad est\u00e1 sobrevalorada. No creas todo lo que piensas. \u00bb<\/strong><\/p>\n<p>Parte de la serie cerrada IRONY &#038; EDGE (Obra n.\u00ba 1 de 5).<br \/>Tecnica: acrilico, inchiostro fotoluminescente, pigmenti interferenziali e neon, collage su tela, tecnica mixed-media 3D, superficie strutturata a mano (INK3D Rebel Technique).<\/p>\n<p>Un paradosso digitale in forma analogica. Un kiwi che finge di essere il sole. Un hashtag che mente. Ci\u00f2 che di giorno appare assurdo segue di notte una propria logica.   <\/p>\n<p>ERROR 404: TRUTH NOT FOUND esplora la percezione, l\u2019autoironia e l\u2019instabilit\u00e0 della certezza. L\u2019opera si muove tra umorismo e disturbo, superficie e proiezione, visibilit\u00e0 e convinzione. Nulla all\u2019interno della composizione chiede di essere creduto completamente \u2014 ed \u00e8 proprio questo il punto.  <\/p>\n<p>La sua ironia \u00e8 deliberata. Mai rumorosa, sempre precisa. Una ribellione silenziosa contro l\u2019ossessione della certezza in un mondo costantemente alla ricerca di prove.  <\/p>\n<p>All\u2019interno del sistema K-NY, l\u2019opera rappresenta lo stato di impulso di IRONY &#038; EDGE \u2014 la prima frattura della percezione, dove la contraddizione diventa consapevolezza e l\u2019umorismo diventa struttura.<\/p>\n<p>Pieza original y \u00fanica.<br \/>Firmada, certificada y disponible a solicitud.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-THINK-BIG-\u2013-REBEL-T.jpg\u00bb title_text=\u00bbScreenshot\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb parallax=\u00bbon\u00bb width=\u00bb80%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_cta _builder_version=\u00bb4.27.7&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbrgba(0,0,0,0)\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 90%|#000000 100%\u00bb button_bg_color_gradient_start=\u00bb#ffffff\u00bb button_bg_color_gradient_start_position=\u00bb90%\u00bb button_bg_color_gradient_end=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bb|700|||||||\u00bb button_custom_padding=\u00bb|0px||0px||true\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb-120px|40px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_margin=\u00bb|-41px||80px|false|false\u00bb custom_margin_tablet=\u00bb||-60px|\u00bb custom_margin_last_edited=\u00bboff|tablet\u00bb custom_padding=\u00bb||25px||false|false\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_horizontal=\u00bb-70px\u00bb box_shadow_vertical=\u00bb70px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.1)\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb0px\u00bb box_shadow_vertical_button=\u00bb1px\u00bb box_shadow_blur_button=\u00bb0px\u00bb box_shadow_color_button=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><span style=\"color: #dfb758;\">Originales ocultos.<\/span><\/h3>\n<p><span style=\"color: #ffcc00;\"><\/span><\/p>\n<p>M\u00e1s all\u00e1 de la colecci\u00f3n p\u00fablica existe una capa m\u00e1s silenciosa del sistema K-NY \u2014 un espacio donde las obras permanecen intencionalmente in\u00e9ditas, preservadas para coleccionistas que entienden la rareza como una forma de precisi\u00f3n cultural.<\/p>\n<p>Los Private Releases y la Vaulted Collection revelan obras que permanecen fuera de la visibilidad p\u00fablica: originales mantenidos con discreci\u00f3n y liberados \u00fanicamente a trav\u00e9s del di\u00e1logo personal.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb11px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/k-ny.art\/es\/the-vault\/\u00bb button_text=\u00bbEnter the Vault\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#DFB758&#8243; button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bb#DFB758&#8243; button_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb button_use_icon=\u00bboff\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px|||||\u00bb custom_padding=\u00bb25px||13px|||\u00bb saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>AUTHENTICITY &#038; ARCHIVING<\/h4>\n<p>Cada obra es una pieza \u00fanica y forma parte de un Cluster \u2014 una serie cerrada de cinco obras.<\/p>\n<p>Todas las obras han sido firmadas personalmente, numeradas y asignadas con un c\u00f3digo oficial K-NY por Ki\u00e9ra Nagy (K-NY).<\/p>\n<p>Cada obra est\u00e1 registrada dentro del Archivo K-NY y acompa\u00f1ada por un Certificado de Autenticidad.<\/p>\n<p>No existen reproducciones ni ediciones..<\/p>\n<p>K-NY no produce \u2014 publica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb14px|||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4 style=\"text-align: left;\">Night Colors. Illumination in the Dark. <b><\/b><\/h4>\n<p>K-NY no desaparece por la noche.<br \/>Se transforma.<\/p>\n<p>Cuando la luz desaparece, otra capa de la obra comienza a emerger.<br \/>Cargados por luz diurna, luz artificial o luz negra, los elementos fotoluminiscentes activan la superficie y desplazan la percepci\u00f3n de la obra..<\/p>\n<p>Lo que durante el d\u00eda parece controlado y silencioso puede volverse luminoso, inestable o psicol\u00f3gicamente cargado en la oscuridad.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">La obra deja de existir como una imagen fija.<br \/>Comienza a operar a trav\u00e9s de transformaci\u00f3n, memoria y percepci\u00f3n.<\/p>\n<p>La luz no se utiliza como efecto.<br \/>Funciona como estructura, activaci\u00f3n y lenguaje.<\/p>\n<p>La noche no repite la obra.<br \/>Revela otro estado de ella.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.27.4&#8243; max_width=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/04\/K-NY-Artwork-ZERO-IN-scaled.jpeg\u00bb alt=\u00bbK-NY artwork ZERO IN \u2013 focused luminous acrylic art from the FOCUS &amp; STRENGTH cluster\u00bb title_text=\u00bbK-NY Artwork ZERO IN\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb _builder_version=\u00bb4.27.6&#8243; background_enable_image=\u00bboff\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb40%\u00bb background_position=\u00bbbottom_left\u00bb max_width=\u00bb800px\u00bb max_width_tablet=\u00bb560px\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb||\u00bb custom_padding=\u00bb||40px|78px||\u00bb custom_padding_tablet=\u00bb40px|30px|0px|0px\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb background_last_edited=\u00bbon|desktop\u00bb background_position_tablet=\u00bbtop_right\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.2)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_cta title=\u00bbObras disponibles\u00bb button_url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb button_text=\u00bbNo es para todos \u2014 descubre por qu\u00e9.\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbrgba(0,0,0,0)\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 90%|#000000 100%\u00bb button_bg_color_gradient_start=\u00bb#ffffff\u00bb button_bg_color_gradient_start_position=\u00bb90%\u00bb button_bg_color_gradient_end=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb button_custom_padding=\u00bb|0px||0px||true\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb-120px|40px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_margin_tablet=\u00bb||-60px|\u00bb custom_margin_last_edited=\u00bboff|tablet\u00bb link_option_url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_horizontal=\u00bb-70px\u00bb box_shadow_vertical=\u00bb70px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.1)\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb0px\u00bb box_shadow_vertical_button=\u00bb1px\u00bb box_shadow_blur_button=\u00bb0px\u00bb box_shadow_color_button=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Seleccionadas.<br \/>Nunca repetidas.<\/p>\n<p>Cada obra es una declaraci\u00f3n aut\u00f3noma: f\u00edsica, luminosa, absoluta.<\/p>\n<p>La percepci\u00f3n abre espacios emocionales.<\/p>\n<p>No eliges un K-NY.<br \/>Es \u00e9l quien te elige.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_repeat=\u00bbrepeat-y\u00bb min_height=\u00bb554.4px\u00bb custom_margin=\u00bb||29px|||\u00bb custom_padding=\u00bb0px|||||\u00bb global_module=\u00bb697&#8243; saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]En K-NY, la irritaci\u00f3n nunca es un accidente.<br \/>Marca el momento en que el pensamiento se niega a obedecer.<\/p>\n<p>K-NY representa lujo con inteligencia.<br \/>Y un gui\u00f1o luminoso.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>COLLECTOR POSITIONING (2026)<br \/>K-NY define el valor a trav\u00e9s de la rareza, la percepci\u00f3n y la relevancia sist\u00e9mica.<br \/>Cada obra es \u00fanica, firmada, certificada y posicionada dentro de una arquitectura de cl\u00faster cerrada.<br \/>Las obras publicadas forman la capa visible del sistema.<br \/>Otras existen exclusivamente como Private Release, Vaulted Work o ausencia controlada.<br \/>Precio a petici\u00f3n.<br \/>K-NY no produce \u2014 publica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_menu menu_style=\u00bbcentered\u00bb disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_menu][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; border_width_top=\u00bb2px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Copyright<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label<br \/>Todos los derechos reservados.<br \/>Todas las obras y contenidos de este sitio web \u2014 incluidas im\u00e1genes, textos y dise\u00f1os \u2014 est\u00e1n protegidos por derechos de autor. Queda prohibida cualquier reproducci\u00f3n, distribuci\u00f3n o modificaci\u00f3n sin el consentimiento previo por escrito de la artista. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb20px\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">K-NY <\/span><br \/>HABLA DIRECTAMENTE.<\/strong><\/p>\n<p>Sin agentes. Sin filtros.<br \/>Si una obra capt\u00f3 tu atenci\u00f3n,<br \/>di cu\u00e1l \u2014 y por qu\u00e9.<br \/>El di\u00e1logo comienza solo<br \/>cuando la intenci\u00f3n es clara. <\/p>\n<h3><b><\/b><\/h3>\n<p><strong><span style=\"color: #808080;\">ESTUDIO (Europa)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/k-ny.art\/es\/contacto\/\">Visitar p\u00e1gina de contacto <span>\u2192<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">DESCRIPTION<\/span><\/strong><\/p>\n<p>K-NY Studio \u2013 Oficina<br \/>Ki\u00e9ra Nagy<br \/>Koendgenstr. 3<br \/>45131 Essen, Alemania<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><br \/>HORARIO<\/span><\/strong><\/p>\n<p>Visitas al estudio solo con cita previa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">INFORMACI\u00d3N<\/span><\/strong><\/p>\n<p>Los precios no incluyen IVA, env\u00edo ni seguro.<br \/>Las obras originales de Ki\u00e9ra Nagy (K-NY) est\u00e1n sujetas al tipo reducido de IVA del 7 % seg\u00fan la legislaci\u00f3n fiscal alemana (\u00a7 12 Abs. 2 Nr. 1 UStG y Anexo 2).<br \/>Para las exportaciones fuera de la UE, el IVA no es aplicable.<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label \u2013 Todos los derechos reservados.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_2_font=\u00bb||||||||\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">SEGUIR<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb4.27.6&#8243; custom_margin=\u00bb-20px|||-10px\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb-20px||\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb filter_invert=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb icon_color__hover=\u00bb#e02b20&#8243;][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/kny.luxuryart\/\u00bb _builder_version=\u00bb4.27.5&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/kny.luxuryart\/\u00bb _builder_version=\u00bb4.27.6&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bblinkedin\u00bb url=\u00bbhttp:\/\/www.linkedin.com\/in\/kiera-nagy\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; background_enable_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Suscr\u00edbete<\/h3>\n<p>al bolet\u00edn informativo y s\u00e9 el primero en descubrir nuevas obras de arte, exposiciones e informaci\u00f3n exclusiva y avances.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00bbSlavaET|11a914d1cc\u00bb first_name_field=\u00bboff\u00bb last_name_field=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; form_field_background_color=\u00bb#f3f3f4&#8243; form_field_custom_padding=\u00bb12px||12px||true\u00bb header_font=\u00bbMontserrat|||on|||||\u00bb header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb5px\u00bb header_line_height=\u00bb1.8em\u00bb form_field_font=\u00bb||||||||\u00bb form_field_font_size=\u00bb14px\u00bb use_background_color=\u00bboff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bb|700|||||||\u00bb button_custom_padding=\u00bb12px||12px||true\u00bb background_layout=\u00bblight\u00bb custom_margin=\u00bb-39px||\u00bb border_radii_fields=\u00bbon|0px|0px|0px|0px\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_signup][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Las obras de K-NY se publican en sistemas cerrados y se sit\u00faan en colecciones privadas e institucionales.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CLUSTER IRONY &#038; EDGE &nbsp; IRONY &#038; EDGE &#8211; Truth glitches. Irony cuts. La verdad titubea.La iron\u00eda corta. IRONY &#038; EDGE es un cluster cerrado compuesto por cinco obras. Dentro del sistema K-NY, explora la relaci\u00f3n entre percepci\u00f3n, distancia y claridad. Impulso \u2192 Expansi\u00f3n \u2192 Consciencia \u2192 Umbral \u2192 Estado La distancia se convierte en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2240","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IRONY &amp; EDGE \u2014 Cluster \/ K-NY<\/title>\n<meta name=\"description\" content=\"IRONY &amp; EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IRONY &amp; EDGE \u2014 Cluster \/ K-NY\" \/>\n<meta property=\"og:description\" content=\"IRONY &amp; EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/\" \/>\n<meta property=\"og:site_name\" content=\"k-ny.art\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-05T09:09:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/serie-cerrada-irony-edge\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/es\\\/serie-cerrada-irony-edge\\\/\",\"name\":\"IRONY & EDGE \u2014 Cluster \\\/ K-NY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\"},\"datePublished\":\"2025-09-17T21:23:43+00:00\",\"dateModified\":\"2026-07-05T09:09:36+00:00\",\"description\":\"IRONY & EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/serie-cerrada-irony-edge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-ny.art\\\/es\\\/serie-cerrada-irony-edge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/serie-cerrada-irony-edge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-ny.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cluster-IRONY- EDGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"name\":\"k-ny.art\",\"description\":\"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-ny.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\",\"name\":\"k-ny.art\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"contentUrl\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"width\":2346,\"height\":1644,\"caption\":\"k-ny.art\"},\"image\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IRONY & EDGE \u2014 Cluster \/ K-NY","description":"IRONY & EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/","og_locale":"es_ES","og_type":"article","og_title":"IRONY & EDGE \u2014 Cluster \/ K-NY","og_description":"IRONY & EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.","og_url":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/","og_site_name":"k-ny.art","article_modified_time":"2026-07-05T09:09:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/","url":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/","name":"IRONY & EDGE \u2014 Cluster \/ K-NY","isPartOf":{"@id":"https:\/\/k-ny.art\/#website"},"datePublished":"2025-09-17T21:23:43+00:00","dateModified":"2026-07-05T09:09:36+00:00","description":"IRONY & EDGE \u2014 a closed cluster of five works where irony becomes precision and rupture becomes structure. Conceptual tension articulated through light, material, and system.","breadcrumb":{"@id":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-ny.art\/es\/serie-cerrada-irony-edge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-ny.art\/"},{"@type":"ListItem","position":2,"name":"Cluster-IRONY- EDGE"}]},{"@type":"WebSite","@id":"https:\/\/k-ny.art\/#website","url":"https:\/\/k-ny.art\/","name":"k-ny.art","description":"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.","publisher":{"@id":"https:\/\/k-ny.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-ny.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/k-ny.art\/#organization","name":"k-ny.art","url":"https:\/\/k-ny.art\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/","url":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","contentUrl":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","width":2346,"height":1644,"caption":"k-ny.art"},"image":{"@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/comments?post=2240"}],"version-history":[{"count":153,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2240\/revisions"}],"predecessor-version":[{"id":40866,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2240\/revisions\/40866"}],"wp:attachment":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/media?parent=2240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}