{"id":2659,"date":"2025-09-14T17:06:16","date_gmt":"2025-09-14T15:06:16","guid":{"rendered":"https:\/\/k-ny.art\/free-love\/"},"modified":"2026-06-28T19:02:10","modified_gmt":"2026-06-28T17:02:10","slug":"free-love","status":"publish","type":"page","link":"https:\/\/k-ny.art\/es\/free-love\/","title":{"rendered":"FREE LOVE"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbWork\u00bb _builder_version=\u00bb4.27.6&#8243; background_enable_image=\u00bboff\u00bb background_size=\u00bbinitial\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb0px||1px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||8px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/05\/Bildschirmfoto-2026-05-11-um-13.27.02.png\u00bb alt=\u00bbFREE LOVE by K-NY \u2014 photoluminescent conceptual artwork activated in darkness, dual-spectrum composition revealing structural light within spatial context\u00bb title_text=\u00bbFREE LOVE \u2014 night activation in space \/ K-NY\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||44px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|||0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: right;\">Conceptual Rebellion\u2122 \u2014<span class=\"Apple-converted-space\"> <\/span><br \/>art that thinks in light and speaks in the dark.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p data-start=\"641\" data-end=\"685\" style=\"text-align: right;\">The light is not an effect.<br data-start=\"668\" data-end=\"671\"\/>It is meaning.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00bboff|phone\u00bb _builder_version=\u00bb4.16&#8243; background_position=\u00bbbottom_center\u00bb custom_padding_tablet=\u00bb17vw||17vw||false\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb|500|||||||\u00bb header_2_text_align=\u00bbcenter\u00bb header_2_font_size=\u00bb56px\u00bb header_2_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|&#8211;et_global_heading_font_weight||on|||||\u00bb header_3_text_align=\u00bbcenter\u00bb header_3_text_color=\u00bbrgba(0,0,0,0.35)\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb2em\u00bb transform_translate_linked=\u00bboff\u00bb max_width=\u00bb700px\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb module_alignment=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb26px\u00bb header_2_font_size_last_edited=\u00bbon|tablet\u00bb header_3_font_size_phone=\u00bb10px\u00bb header_3_font_size_last_edited=\u00bboff|desktop\u00bb module_alignment_last_edited=\u00bboff|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>ARTWORK<\/h3>\n<h2>FREE LOVE<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]Ella no lo llama amor. Ella lo vive.<br \/>\nUna mirada, un temblor, una chispa \u2014 y todo comienza. <\/p>\n<p>El color explota entre el pensamiento y la emoci\u00f3n.<br \/>\nEl ne\u00f3n susurra palabras que revelan m\u00e1s de lo que dicen:<br \/>\nDesire. Fantasy. Kiss me. Bite me.   <\/p>\n<p>Entre el control y el \u00e9xtasis surge un espacio \u2014 crudo, luminoso, honesto.<br \/>\nDe d\u00eda, intenso. De noche, sin l\u00edmites: las l\u00edneas brillan, los pensamientos respiran luz. <\/p>\n<p>FREE LOVE no es romance.<br \/>Es energ\u00eda \u2014 liberada de la verg\u00fcenza, el control y la proyecci\u00f3n.<br \/>Una celebraci\u00f3n del deseo como acto consciente de libertad y presencia.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,3_5,1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY-FREE-LOVE-NF1.jpg\u00bb title_text=\u00bbScreenshot\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb59px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb||||||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h5 style=\"text-align: center;\">Lo que lo hace \u00fanico: La fotoluminiscencia integrada transforma cada obra a lo largo del d\u00eda.<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY-FREE-LOVE-NF1.jpg\u00bb title_text=\u00bbScreenshot\u00bb show_in_lightbox=\u00bbon\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; border_width_all=\u00bb20px\u00bb border_color_all=\u00bb#ffffff\u00bb border_width_all_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb1px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.34)\u00bb global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon\u00bb box_shadow_color__hover=\u00bb#000000&#8243; border_width_all__hover=\u00bb30px\u00bb border_width_all__hover_enabled=\u00bbon\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb134%|134%\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b>De d\u00eda<\/b><\/p>\n<p>arte 3D poderoso, lleno de color y forma<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY_Free-Love-evening-1.jpg\u00bb title_text=\u00bbScreenshot\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; border_width_all=\u00bb20px\u00bb border_color_all=\u00bb#ffffff\u00bb border_width_all_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb1px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.34)\u00bb global_colors_info=\u00bb{}\u00bb box_shadow_color__hover_enabled=\u00bbon\u00bb box_shadow_color__hover=\u00bb#000000&#8243; border_width_all__hover=\u00bb30px\u00bb border_width_all__hover_enabled=\u00bbon\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb134%|134%\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b>Al atardecer<\/b><\/p>\n<p>sutiles acentos luminosos cambian el enfoque<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY_Free-Love-night-1.jpg\u00bb title_text=\u00bbScreenshot\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; border_width_all=\u00bb20px\u00bb border_color_all=\u00bb#ffffff\u00bb border_width_all_last_edited=\u00bboff|desktop\u00bb box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_vertical=\u00bb0px\u00bb box_shadow_spread=\u00bb1px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.34)\u00bb global_colors_info=\u00bb{}\u00bb box_shadow_color__hover=\u00bb#000000&#8243; box_shadow_color__hover_enabled=\u00bbon\u00bb border_width_all__hover=\u00bb30px\u00bb border_width_all__hover_enabled=\u00bbon\u00bb transform_styles__hover_enabled=\u00bbon|hover\u00bb transform_scale__hover_enabled=\u00bbon|hover\u00bb transform_translate__hover_enabled=\u00bbon|desktop\u00bb transform_rotate__hover_enabled=\u00bbon|desktop\u00bb transform_skew__hover_enabled=\u00bbon|desktop\u00bb transform_origin__hover_enabled=\u00bbon|desktop\u00bb transform_scale__hover=\u00bb134%|134%\u00bb][\/et_pb_image][et_pb_text ul_position=\u00bbinside\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb ul_font=\u00bb||||||||\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700|||||||\u00bb header_3_font_size=\u00bb14px\u00bb header_3_line_height=\u00bb1.3em\u00bb text_orientation=\u00bbcenter\u00bb text_text_align=\u00bbcenter\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b>De noche<\/b><\/p>\n<p>el mensaje central brilla \u2013 reducido a lo esencial, intensamente palpable<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/F_cutout_white_Q2_inside_transparent1.png\u00bb title_text=\u00bbScreenshot\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY-FREE-LOVE-NF1.jpg\u00bb parallax=\u00bbon\u00bb width=\u00bb75%\u00bb module_alignment=\u00bbright\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/CC.png\u00bb title_text=\u00bbCC\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb110px\u00bb max_width_tablet=\u00bb70px\u00bb max_width_phone=\u00bb35px\u00bb max_width_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bb003e9429-8e11-4d9e-968b-8881092bbf81&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb|600|||||||\u00bb header_2_text_color=\u00bb#000000&#8243; header_2_font_size=\u00bb48px\u00bb header_2_line_height=\u00bb1.1em\u00bb custom_margin=\u00bb||0px||false|false\u00bb header_2_font_size_tablet=\u00bb32px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|desktop\u00bb header_2_line_height_tablet=\u00bb1.2em\u00bb header_2_line_height_phone=\u00bb\u00bb header_2_line_height_last_edited=\u00bbon|phone\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1><strong><\/strong><\/h1>\n<h1><strong><\/strong><\/h1>\n<h1><strong>No rules.<\/strong><\/h1>\n<h1><\/h1>\n<p>&nbsp;<\/p>\n<h1><strong>Just love.<\/strong><\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00bboff|phone\u00bb _builder_version=\u00bb4.16&#8243; background_position=\u00bbbottom_center\u00bb custom_padding_tablet=\u00bb17vw||17vw||false\u00bb use_custom_width=\u00bbon\u00bb width_unit=\u00bboff\u00bb custom_width_percent=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb header_font=\u00bb||||||||\u00bb header_2_font=\u00bb|500|||||||\u00bb header_2_font_size=\u00bb56px\u00bb header_2_line_height=\u00bb1.3em\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_text_color=\u00bbrgba(0,0,0,0.35)\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb2em\u00bb transform_translate_linked=\u00bboff\u00bb text_orientation=\u00bbcenter\u00bb max_width=\u00bb700px\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb module_alignment=\u00bbcenter\u00bb header_2_font_size_tablet=\u00bb40px\u00bb header_2_font_size_phone=\u00bb26px\u00bb header_2_font_size_last_edited=\u00bbon|phone\u00bb header_3_font_size_phone=\u00bb10px\u00bb header_3_font_size_last_edited=\u00bboff|desktop\u00bb module_alignment_last_edited=\u00bboff|desktop\u00bb text_text_align=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">ARTWORK<\/p>\n<h1 style=\"text-align: left;\">FREE LOVE<\/h1>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">T\u00edtulo: FREE LOVE, parte de la serie INK3D Rebel<br \/>Serie cerrada (Cluster): LOVE &#038; DESIRE (Obra n.\u00ba 1 de 5)<br \/>A\u00f1o: 2025<br \/>Medio: Acr\u00edlico, tinta fotoluminiscente, letras de ne\u00f3n, collage sobre lienzo, t\u00e9cnica mixta 3D, superficie texturizada a mano, t\u00e9cnica INK3D Rebel<\/p>\n<p style=\"text-align: left;\">Tama\u00f1o del lienzo:<br \/>140 \u00d7 100 \u00d7 4,5 cm (Alto \u00d7 Ancho \u00d7 Profundidad)<br \/>55 \u00d7 40 \u00d7 1,8 in (Alto \u00d7 Ancho \u00d7 Profundidad)<br \/>Tama\u00f1o de la obra:<br \/>145 \u00d7 100 \u00d7 18 cm (Alto \u00d7 Ancho \u00d7 Profundidad)<br \/>57 \u00d7 40 \u00d7 7 in (Alto \u00d7 Ancho \u00d7 Profundidad)<\/p>\n<p style=\"text-align: left;\">Caracter\u00edsticas especiales: Obra original, pieza \u00fanica. Textura trabajada a mano.<br \/>Composici\u00f3n de doble espectro \u2013 transformaci\u00f3n visible entre el d\u00eda y la noche; elementos fotoluminiscentes activos en la oscuridad.  Letras de ne\u00f3n que se activan bajo luz negra.<\/p>\n<p style=\"text-align: left;\"><span>DESCRIPTION<br \/><\/span><br \/>FREE LOVE es una declaraci\u00f3n 3D audaz y luminosa sobre la libertad de amar sin l\u00edmites.<br \/>En el centro aparece el rostro de una mujer \u2014 gui\u00f1ando un ojo, medio velado, indomable. Entre sus ojos estalla el color como una explosi\u00f3n de pensamiento \u2014 energ\u00eda transformada en emoci\u00f3n. <\/p>\n<p style=\"text-align: left;\">A su alrededor, palabras de ne\u00f3n emergen: <i>Desire. Craving. Heat. Fantasy. Free Love. Seduce. Kiss me.       Bite me. <\/i>Fragmentos de pasi\u00f3n, juego y rebeld\u00eda \u2013 cada palabra brilla como un pulso el\u00e9ctrico.<\/p>\n<p style=\"text-align: left;\">En la base, cuatro letras monumentales en 3D forman la palabra LOVE.<br \/>Acr\u00edlico, tinta fotoluminiscente, letras de ne\u00f3n y collage se fusionan en una composici\u00f3n t\u00e1ctil y vibrante. De d\u00eda irradia intensidad; de noche, se transforma \u2013 l\u00edneas luminosas y efectos de luz negra revelan una segunda dimensi\u00f3n. <\/p>\n<p style=\"text-align: left;\">FREE LOVE no es una pintura \u2013 es una experiencia.<br \/>Una celebraci\u00f3n de la libertad, del deseo y de la alegr\u00eda sin culpa.<br \/>Celebra el deseo no como exceso, sino como energ\u00eda vital.<\/p>\n<p style=\"text-align: left;\">Como todas las obras de K-NY, FREE LOVE combina precisi\u00f3n y provocaci\u00f3n \u2013 arte que se siente.<\/p>\n<p style=\"text-align: left;\">COLLECTOR VERSION<\/p>\n<p style=\"text-align: left;\">Una obra para mentes que ven m\u00e1s all\u00e1 de la superficie.<br \/>FREE LOVE entiende el deseo como libertad \u2014 no como exceso, sino como energ\u00eda.<br \/>Para coleccionistas que se atreven a sentir sin pedir disculpas.<\/p>\n<p style=\"text-align: left;\">Firma: Logo en el frente, firmado en el lateral y en el reverso. Certificado de autenticidad incluido.<br \/>Disponibilidad: Original<br \/>Serie cerrada: LOVE &#038; DESIRE \u2013 Obra n.\u00ba 1 de 5 <\/p>\n<p style=\"text-align: left;\">Precio a petici\u00f3n<\/p>\n<p style=\"text-align: left;\">Pieza \u00fanica, firmada y certificada.<\/p>\n<p style=\"text-align: left;\">El valor surge de la percepci\u00f3n, la rareza y la precisi\u00f3n conceptual \u2014 no del tama\u00f1o.<\/p>\n<p style=\"text-align: left;\">Un K-NY no se mide \u2014 se experimenta.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>WITHIN THE SYSTEM<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Para coleccionistas que entienden la conexi\u00f3n como una decisi\u00f3n consciente.<br \/>No es una promesa de emoci\u00f3n \u2014 sino el fin de la distancia.<br \/>Una declaraci\u00f3n de apertura en una colecci\u00f3n.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Disponible para colocaci\u00f3n institucional y privada.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]Esta obra marca el impulso.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><a href=\"https:\/\/k-ny.art\/es\/masterpieces\/\">Masterpieces<\/a><br \/><a href=\"https:\/\/k-ny.art\/es\/serie-cerrada\/\">\u2192 System<\/a><br \/><a href=\"https:\/\/k-ny.art\/es\/contacto\/\">\u2192 Studio<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>Detalles &#038; Inspiraci\u00f3n<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb18px|auto||auto||\u00bb custom_padding=\u00bb||14px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb21114,7722,28121,2649,2651,7720,2653,2654,2652,2655,2657,2656,2648,2658,171,169&#8243; show_title_and_caption=\u00bboff\u00bb zoom_icon_color=\u00bb#000000&#8243; hover_icon=\u00bb\uf592||fa||400&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>M\u00c1S ALL\u00c1 DEL LIENZO<\/h4>\n<p>Free Love is not a quiet painting. It strikes \u2014 straight to the heart, straight to the mind.<br \/>A woman\u2019s face, a playful wink, a translucent blindfold \u2014 a game of revealing and restraint.<br \/>From between her eyes, color bursts outward \u2014 thought, emotion, fantasy \u2014 the epicenter of desire. <\/p>\n<p>Across the canvas, neon words ignite: <i>Desire. Craving. Heat. Fantasy. Bite me. Seduce. Play with me.      <\/i><br \/>They don\u2019t whisper \u2014 they burn. They touch the skin, electrify the senses, provoke the pulse.<br \/>And beneath it all, massive and magnetic: four sculptural letters \u2014 LOVE. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>De noche, la obra se transforma.<br \/>Los acentos fotoluminiscentes y la luz negra despiertan el texto oculto \u2014 brillante, provocador, vivo.<br \/>El espacio se convierte en un escenario donde la libertad, el deseo y el amor bailan sin censura.<\/p>\n<p>Free Love no pide permiso. Es un himno.<br \/>Un llamado a la libertad, al valor, al placer y al juego \u2014 sin filtros, sin l\u00edmites, inolvidable. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/k-ny.art\/inquiry\/\u00bb button_text=\u00bbSolicitud de obra\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#8F8F8F\u00bb button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bb#8F8F8F\u00bb button_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb button_use_icon=\u00bboff\u00bb animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Para coleccionistas con actitud.<br \/>Acceso privado al \u00e1rea de coleccionistas K-NY bajo solicitud.<br \/><span style=\"color: #999999;\"><a href=\"https:\/\/k-ny.art\/collector\/\" style=\"color: #999999;\">\u2192 Acceso para coleccionistas<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||7px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">Esta obra forma parte de una serie cerrada exclusiva. Descubre las cinco obras de esta colecci\u00f3n completa. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb11px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/k-ny.art\/es\/serie-cerrada-love-desire\/\u00bb button_text=\u00bbVer la serie cerrada\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb15px\u00bb button_text_color=\u00bb#8F8F8F\u00bb button_bg_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_color=\u00bb#8F8F8F\u00bb button_font=\u00bb&#8211;et_global_heading_font||||||||\u00bb button_icon=\u00bb&#x24;||divi||400&#8243; animation_style=\u00bbslide\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px|||||\u00bb custom_padding=\u00bb25px||13px|||\u00bb global_module=\u00bb986&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>AUTHENTICITY &#038; ARCHIVING<\/h4>\n<p>Cada obra es una pieza \u00fanica y forma parte de un Cluster \u2014 una serie cerrada de cinco obras.<\/p>\n<p>Todas las obras han sido firmadas personalmente, numeradas y asignadas con un c\u00f3digo oficial K-NY por Ki\u00e9ra Nagy (K-NY).<\/p>\n<p>Cada obra est\u00e1 registrada dentro del Archivo K-NY y acompa\u00f1ada por un Certificado de Autenticidad.<\/p>\n<p>No existen reproducciones ni ediciones..<\/p>\n<p>K-NY no produce \u2014 publica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb14px|||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4 style=\"text-align: left;\">Night Colors. Illumination in the Dark. <b><\/b><\/h4>\n<p>K-NY no desaparece por la noche.<br \/>Se transforma.<\/p>\n<p>Cuando la luz desaparece, otra capa de la obra comienza a emerger.<br \/>Cargados por luz diurna, luz artificial o luz negra, los elementos fotoluminiscentes activan la superficie y desplazan la percepci\u00f3n de la obra..<\/p>\n<p>Lo que durante el d\u00eda parece controlado y silencioso puede volverse luminoso, inestable o psicol\u00f3gicamente cargado en la oscuridad.[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">La obra deja de existir como una imagen fija.<br \/>Comienza a operar a trav\u00e9s de transformaci\u00f3n, memoria y percepci\u00f3n.<\/p>\n<p>La luz no se utiliza como efecto.<br \/>Funciona como estructura, activaci\u00f3n y lenguaje.<\/p>\n<p>La noche no repite la obra.<br \/>Revela otro estado de ella.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.27.4&#8243; max_width=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/04\/K-NY-Artwork-ZERO-IN-scaled.jpeg\u00bb alt=\u00bbK-NY artwork ZERO IN \u2013 focused luminous acrylic art from the FOCUS &amp; STRENGTH cluster\u00bb title_text=\u00bbK-NY Artwork ZERO IN\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb _builder_version=\u00bb4.27.6&#8243; background_enable_image=\u00bboff\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb40%\u00bb background_position=\u00bbbottom_left\u00bb max_width=\u00bb800px\u00bb max_width_tablet=\u00bb560px\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb||\u00bb custom_padding=\u00bb||40px|78px||\u00bb custom_padding_tablet=\u00bb40px|30px|0px|0px\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb background_last_edited=\u00bbon|desktop\u00bb background_position_tablet=\u00bbtop_right\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.2)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_cta title=\u00bbObras disponibles\u00bb button_url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb button_text=\u00bbNo es para todos \u2014 descubre por qu\u00e9.\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb header_font_size=\u00bb18px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbrgba(0,0,0,0)\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 90%|#000000 100%\u00bb button_bg_color_gradient_start=\u00bb#ffffff\u00bb button_bg_color_gradient_start_position=\u00bb90%\u00bb button_bg_color_gradient_end=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_color=\u00bbRGBA(255,255,255,0)\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb button_custom_padding=\u00bb|0px||0px||true\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb-120px|40px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_margin_tablet=\u00bb||-60px|\u00bb custom_margin_last_edited=\u00bboff|tablet\u00bb link_option_url=\u00bbhttps:\/\/k-ny.art\/es\/obras\/\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_horizontal=\u00bb-70px\u00bb box_shadow_vertical=\u00bb70px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.1)\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb0px\u00bb box_shadow_vertical_button=\u00bb1px\u00bb box_shadow_blur_button=\u00bb0px\u00bb box_shadow_color_button=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Seleccionadas.<br \/>Nunca repetidas.<\/p>\n<p>Cada obra es una declaraci\u00f3n aut\u00f3noma: f\u00edsica, luminosa, absoluta.<\/p>\n<p>La percepci\u00f3n abre espacios emocionales.<\/p>\n<p>No eliges un K-NY.<br \/>Es \u00e9l quien te elige.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; _builder_version=\u00bb4.27.4&#8243; max_width=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_image src=\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/05\/FOCUS-STRENGTH-\u2014-K-NY-Cluster-Icon.png\u00bb alt=\u00bbGlowing circular light structure representing the K-NY cluster FOCUS &amp; STRENGTH \u2014 controlled energy flow, precision, and perceptual stability within the K-NY system.\u00bb title_text=\u00bbFOCUS &amp; STRENGTH \u2014 K-NY Cluster Icon\u00bb url=\u00bbhttps:\/\/k-ny.art\/es\/serie-cerrada\/\u00bb _builder_version=\u00bb4.27.6&#8243; background_enable_image=\u00bboff\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb40%\u00bb background_position=\u00bbbottom_left\u00bb max_width=\u00bb800px\u00bb max_width_tablet=\u00bb560px\u00bb max_width_phone=\u00bb\u00bb max_width_last_edited=\u00bbon|tablet\u00bb module_alignment=\u00bbright\u00bb custom_margin=\u00bb||\u00bb custom_padding=\u00bb||40px|78px||\u00bb custom_padding_tablet=\u00bb40px|30px|0px|0px\u00bb custom_padding_phone=\u00bb\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb background_last_edited=\u00bbon|desktop\u00bb background_position_tablet=\u00bbtop_right\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb20px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.2)\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.27.4&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_cta title=\u00bbCLUSTER\u00bb button_url=\u00bbhttps:\/\/k-ny.art\/es\/serie-cerrada\/\u00bb button_text=\u00bbSolo quienes est\u00e1n dentro se convierten en parte de ello.\u00bb _builder_version=\u00bb4.27.6&#8243; header_level=\u00bbh3&#8243; header_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb header_font_size=\u00bb20px\u00bb header_line_height=\u00bb1.3em\u00bb body_font=\u00bb||||||||\u00bb background_color=\u00bb#ffffff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bbrgba(0,0,0,0)\u00bb button_bg_color_gradient_stops=\u00bb#ffffff 90%|#000000 100%\u00bb button_bg_color_gradient_start=\u00bb#ffffff\u00bb button_bg_color_gradient_start_position=\u00bb90%\u00bb button_bg_color_gradient_end=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bb|&#8211;et_global_heading_font_weight|||||||\u00bb button_custom_padding=\u00bb|0px||0px||true\u00bb transform_scale_tablet=\u00bb\u00bb transform_scale_phone=\u00bb\u00bb transform_scale_last_edited=\u00bbon|desktop\u00bb transform_translate=\u00bb-120px|40px\u00bb transform_translate_tablet=\u00bb0px|0px\u00bb transform_translate_phone=\u00bb\u00bb transform_translate_last_edited=\u00bbon|phone\u00bb transform_translate_linked=\u00bboff\u00bb transform_rotate_tablet=\u00bb\u00bb transform_rotate_phone=\u00bb\u00bb transform_rotate_last_edited=\u00bbon|desktop\u00bb transform_skew_tablet=\u00bb\u00bb transform_skew_phone=\u00bb\u00bb transform_skew_last_edited=\u00bbon|desktop\u00bb transform_origin_tablet=\u00bb\u00bb transform_origin_phone=\u00bb\u00bb transform_origin_last_edited=\u00bbon|desktop\u00bb transform_styles_last_edited=\u00bbon|phone\u00bb text_orientation=\u00bbleft\u00bb background_layout=\u00bblight\u00bb custom_margin_tablet=\u00bb||-60px|\u00bb custom_margin_last_edited=\u00bboff|tablet\u00bb link_option_url=\u00bbhttps:\/\/k-ny.art\/es\/serie-cerrada\/\u00bb header_font_size_last_edited=\u00bboff|desktop\u00bb transform_styles_tablet=\u00bb\u00bb transform_styles_phone=\u00bb\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_horizontal=\u00bb-70px\u00bb box_shadow_vertical=\u00bb70px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_spread=\u00bb0px\u00bb box_shadow_color=\u00bbrgba(67,58,122,0.1)\u00bb box_shadow_style_button=\u00bbpreset2&#8243; box_shadow_horizontal_button=\u00bb0px\u00bb box_shadow_vertical_button=\u00bb1px\u00bb box_shadow_blur_button=\u00bb0px\u00bb box_shadow_color_button=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>K-NY no trabaja en series.<br \/>Cada Cluster es un sistema art\u00edstico cerrado \u2014 cinco obras, una idea, un campo de tensi\u00f3n. <\/p>\n<p>Una vez completado, un Cluster permanece sellado.<br \/>Sin a\u00f1adidos. Sin cambios. Sin retorno.   <\/p>\n<p>Un Cluster no es una colecci\u00f3n.<br \/>Es un manifiesto en fragmentos. <\/p>\n<p>Cinco perspectivas. Una estructura. <\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_repeat=\u00bbrepeat-y\u00bb min_height=\u00bb554.4px\u00bb custom_margin=\u00bb||29px|||\u00bb custom_padding=\u00bb0px|||||\u00bb global_module=\u00bb697&#8243; saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]En K-NY, la irritaci\u00f3n nunca es un accidente.<br \/>Marca el momento en que el pensamiento se niega a obedecer.<\/p>\n<p>K-NY representa lujo con inteligencia.<br \/>Y un gui\u00f1o luminoso.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>COLLECTOR POSITIONING (2026)<br \/>K-NY define el valor a trav\u00e9s de la rareza, la percepci\u00f3n y la relevancia sist\u00e9mica.<br \/>Cada obra es \u00fanica, firmada, certificada y posicionada dentro de una arquitectura de cl\u00faster cerrada.<br \/>Las obras publicadas forman la capa visible del sistema.<br \/>Otras existen exclusivamente como Private Release, Vaulted Work o ausencia controlada.<br \/>Precio a petici\u00f3n.<br \/>K-NY no produce \u2014 publica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_menu menu_style=\u00bbcentered\u00bb disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_menu][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_5,2_5&#8243; use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb2&#8243; _builder_version=\u00bb4.27.4&#8243; border_width_top=\u00bb2px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Copyright<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label<br \/>Todos los derechos reservados.<br \/>Todas las obras y contenidos de este sitio web \u2014 incluidas im\u00e1genes, textos y dise\u00f1os \u2014 est\u00e1n protegidos por derechos de autor. Queda prohibida cualquier reproducci\u00f3n, distribuci\u00f3n o modificaci\u00f3n sin el consentimiento previo por escrito de la artista. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb20px\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">K-NY <\/span><br \/>HABLA DIRECTAMENTE.<\/strong><\/p>\n<p>Sin agentes. Sin filtros.<br \/>Si una obra capt\u00f3 tu atenci\u00f3n,<br \/>di cu\u00e1l \u2014 y por qu\u00e9.<br \/>El di\u00e1logo comienza solo<br \/>cuando la intenci\u00f3n es clara. <\/p>\n<h3><b><\/b><\/h3>\n<p><strong><span style=\"color: #808080;\">ESTUDIO (Europa)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/k-ny.art\/es\/contacto\/\">Visitar p\u00e1gina de contacto <span>\u2192<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">DESCRIPTION<\/span><\/strong><\/p>\n<p>K-NY Studio \u2013 Oficina<br \/>Ki\u00e9ra Nagy<br \/>Koendgenstr. 3<br \/>45131 Essen, Alemania<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><br \/>HORARIO<\/span><\/strong><\/p>\n<p>Visitas al estudio solo con cita previa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">INFORMACI\u00d3N<\/span><\/strong><\/p>\n<p>Los precios no incluyen IVA, env\u00edo ni seguro.<br \/>Las obras originales de Ki\u00e9ra Nagy (K-NY) est\u00e1n sujetas al tipo reducido de IVA del 7 % seg\u00fan la legislaci\u00f3n fiscal alemana (\u00a7 12 Abs. 2 Nr. 1 UStG y Anexo 2).<br \/>Para las exportaciones fuera de la UE, el IVA no es aplicable.<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label \u2013 Todos los derechos reservados.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_2_font=\u00bb||||||||\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong><span style=\"color: #808080;\">SEGUIR<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb4.27.6&#8243; custom_margin=\u00bb-20px|||-10px\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb-20px||\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb filter_invert=\u00bb100%\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb icon_color__hover=\u00bb#e02b20&#8243;][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/kny.luxuryart\/\u00bb _builder_version=\u00bb4.27.5&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/kny.luxuryart\/\u00bb _builder_version=\u00bb4.27.6&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bblinkedin\u00bb url=\u00bbhttp:\/\/www.linkedin.com\/in\/kiera-nagy\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; background_enable_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_text disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.5&#8243; text_font=\u00bb||||||||\u00bb text_font_size=\u00bb12px\u00bb text_line_height=\u00bb2em\u00bb link_font=\u00bb||||on||||\u00bb link_text_color=\u00bb#666666&#8243; header_font=\u00bb||||||||\u00bb header_text_align=\u00bbleft\u00bb header_3_font=\u00bb|700||on|||||\u00bb header_3_font_size=\u00bb12px\u00bb header_3_letter_spacing=\u00bb5px\u00bb header_3_line_height=\u00bb1.8em\u00bb max_width_tablet=\u00bb70%\u00bb max_width_last_edited=\u00bboff|phone\u00bb header_3_font_size_tablet=\u00bb\u00bb header_3_font_size_phone=\u00bb\u00bb header_3_font_size_last_edited=\u00bbon|desktop\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Suscr\u00edbete<\/h3>\n<p>al bolet\u00edn informativo y s\u00e9 el primero en descubrir nuevas obras de arte, exposiciones e informaci\u00f3n exclusiva y avances.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00bbSlavaET|11a914d1cc\u00bb first_name_field=\u00bboff\u00bb last_name_field=\u00bboff\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.4&#8243; form_field_background_color=\u00bb#f3f3f4&#8243; form_field_custom_padding=\u00bb12px||12px||true\u00bb header_font=\u00bbMontserrat|||on|||||\u00bb header_font_size=\u00bb14px\u00bb header_letter_spacing=\u00bb5px\u00bb header_line_height=\u00bb1.8em\u00bb form_field_font=\u00bb||||||||\u00bb form_field_font_size=\u00bb14px\u00bb use_background_color=\u00bboff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb14px\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#000000&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bb|700|||||||\u00bb button_custom_padding=\u00bb12px||12px||true\u00bb background_layout=\u00bblight\u00bb custom_margin=\u00bb-39px||\u00bb border_radii_fields=\u00bbon|0px|0px|0px|0px\u00bb disabled=\u00bbon\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_signup][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span>Las obras de K-NY se publican en sistemas cerrados y se sit\u00faan en colecciones privadas e institucionales.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conceptual Rebellion\u2122 \u2014 art that thinks in light and speaks in the dark.The light is not an effect.It is meaning.ARTWORK FREE LOVEElla no lo llama amor. Ella lo vive. Una mirada, un temblor, una chispa \u2014 y todo comienza. El color explota entre el pensamiento y la emoci\u00f3n. El ne\u00f3n susurra palabras que revelan m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-2659","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FREE LOVE \u2014 LOVE &amp; DESIRE \/ K-NY<\/title>\n<meta name=\"description\" content=\"FREE LOVE \u2014 a photoluminescent original from the LOVE &amp; DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-ny.art\/es\/free-love\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FREE LOVE \u2014 LOVE &amp; DESIRE \/ K-NY\" \/>\n<meta property=\"og:description\" content=\"FREE LOVE \u2014 a photoluminescent original from the LOVE &amp; DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-ny.art\/es\/free-love\/\" \/>\n<meta property=\"og:site_name\" content=\"k-ny.art\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-28T17:02:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/free-love\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/es\\\/free-love\\\/\",\"name\":\"FREE LOVE \u2014 LOVE & DESIRE \\\/ K-NY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\"},\"datePublished\":\"2025-09-14T15:06:16+00:00\",\"dateModified\":\"2026-06-28T17:02:10+00:00\",\"description\":\"FREE LOVE \u2014 a photoluminescent original from the LOVE & DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/free-love\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-ny.art\\\/es\\\/free-love\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/es\\\/free-love\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-ny.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FREE LOVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"name\":\"k-ny.art\",\"description\":\"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-ny.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\",\"name\":\"k-ny.art\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"contentUrl\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"width\":2346,\"height\":1644,\"caption\":\"k-ny.art\"},\"image\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FREE LOVE \u2014 LOVE & DESIRE \/ K-NY","description":"FREE LOVE \u2014 a photoluminescent original from the LOVE & DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-ny.art\/es\/free-love\/","og_locale":"es_ES","og_type":"article","og_title":"FREE LOVE \u2014 LOVE & DESIRE \/ K-NY","og_description":"FREE LOVE \u2014 a photoluminescent original from the LOVE & DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.","og_url":"https:\/\/k-ny.art\/es\/free-love\/","og_site_name":"k-ny.art","article_modified_time":"2026-06-28T17:02:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-ny.art\/es\/free-love\/","url":"https:\/\/k-ny.art\/es\/free-love\/","name":"FREE LOVE \u2014 LOVE & DESIRE \/ K-NY","isPartOf":{"@id":"https:\/\/k-ny.art\/#website"},"datePublished":"2025-09-14T15:06:16+00:00","dateModified":"2026-06-28T17:02:10+00:00","description":"FREE LOVE \u2014 a photoluminescent original from the LOVE & DESIRE cluster. Attraction as field, intimacy as spatial relation, light as a condition of encounter.","breadcrumb":{"@id":"https:\/\/k-ny.art\/es\/free-love\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-ny.art\/es\/free-love\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-ny.art\/es\/free-love\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-ny.art\/"},{"@type":"ListItem","position":2,"name":"FREE LOVE"}]},{"@type":"WebSite","@id":"https:\/\/k-ny.art\/#website","url":"https:\/\/k-ny.art\/","name":"k-ny.art","description":"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.","publisher":{"@id":"https:\/\/k-ny.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-ny.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/k-ny.art\/#organization","name":"k-ny.art","url":"https:\/\/k-ny.art\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/","url":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","contentUrl":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","width":2346,"height":1644,"caption":"k-ny.art"},"image":{"@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/comments?post=2659"}],"version-history":[{"count":159,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2659\/revisions"}],"predecessor-version":[{"id":39557,"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/pages\/2659\/revisions\/39557"}],"wp:attachment":[{"href":"https:\/\/k-ny.art\/es\/wp-json\/wp\/v2\/media?parent=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}