{"id":14366,"date":"2025-12-19T10:50:03","date_gmt":"2025-12-19T09:50:03","guid":{"rendered":"https:\/\/k-ny.art\/page-zero\/"},"modified":"2026-07-04T01:10:25","modified_gmt":"2026-07-03T23:10:25","slug":"page-zero","status":"publish","type":"page","link":"https:\/\/k-ny.art\/fr\/page-zero\/","title":{"rendered":"PAGE ZERO"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbWork\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb0px||1px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/02\/PAGE-ZERO-G1.png\u00a0\u00bb alt=\u00a0\u00bbInstallation view of PAGE ZERO by K-NY displayed in a minimal architectural space, showing the diptych with central gap and horizontal salt line defining spatial structure and presence.\u00a0\u00bb title_text=\u00a0\u00bbPAGE ZERO. Spatial Presence. \u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb1px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb|||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: right;\">Conceptual Rebellion\u2122 \u2014<span class=\"Apple-converted-space\"> <\/span><br \/>art that thinks in light and speaks in the dark.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p data-start=\"641\" data-end=\"685\" style=\"text-align: right;\">The light is not an effect.<br data-start=\"668\" data-end=\"671\"\/>It is meaning.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_position=\u00a0\u00bbbottom_center\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb17vw||17vw||false\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; text_font=\u00a0\u00bbMontserrat||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|500|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size=\u00a0\u00bb56px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_align=\u00a0\u00bbcenter\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.35)\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb2em\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb10px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><\/h3>\n<p>&nbsp;<\/p>\n<h2>PAGE ZERO<\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,1_5,3_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>L&rsquo;origine n&rsquo;est pas un motif.<br \/>C&rsquo;est un moment.<br \/>Cette \u0153uvre ne montre pas une origine.<br \/>Elle la cr\u00e9e.<br \/>Deux surfaces.<br \/>Une ouverture.<br \/>Une ligne.<br \/>Ce qui est forme le jour,<br \/>devient origine la nuit.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/02\/PAGE-ZERO-D1.png\u00a0\u00bb alt=\u00a0\u00bbFull daylight view of PAGE ZERO, revealing two ultra-matte white canvases separated by a vertical gap, with concentrated salt texture and horizontal extension line.\u00a0\u00bb title_text=\u00a0\u00bbPAGE ZERO. Day Structure. \u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/CC.png\u00a0\u00bb title_text=\u00a0\u00bbCC\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb140px\u00a0\u00bb max_width_tablet=\u00a0\u00bb70px\u00a0\u00bb max_width_phone=\u00a0\u00bb35px\u00a0\u00bb max_width_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bb003e9429-8e11-4d9e-968b-8881092bbf81&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|600|||||||\u00a0\u00bb header_2_text_color=\u00a0\u00bb#000000&Prime; header_2_font_size=\u00a0\u00bb48px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.1em\u00a0\u00bb custom_margin=\u00a0\u00bb||0px||false|false\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb32px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb20px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb header_2_line_height_tablet=\u00a0\u00bb1.2em\u00a0\u00bb header_2_line_height_phone=\u00a0\u00bb\u00a0\u00bb header_2_line_height_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1>The moment<\/h1>\n<h1><\/h1>\n<h1>before everything.<\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/k-ny.art\/wp-content\/uploads\/2026\/02\/PAGE-ZERO-Night-new1.png\u00a0\u00bb alt=\u00a0\u00bbNight view of PAGE ZERO with photoluminescent pigments\u00a0\u00bb title_text=\u00a0\u00bbPAGE ZERO. Night Origin. \u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>La lumi\u00e8re n\u2019est pas vue.<br \/>Elle est comprise \u2014 au-del\u00e0 de l\u2019horizon.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_position=\u00a0\u00bbbottom_center\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb17vw||17vw||false\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bb|500|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb56px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.35)\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb2em\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb10px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: left;\">ARTWORK<\/p>\n<h1 style=\"text-align: left;\">PAGE ZERO<\/h1>\n<p style=\"text-align: left;\">Titre: PAGE ZERO<br \/>S\u00e9rie: INK3D Rebel Serie<br \/>Cluster: FOCUS &#038; STRENGTH (\u0152uvre n\u00b0 2 sur 5)<br \/>Ann\u00e9e: 2026<\/p>\n<p style=\"text-align: left;\">Medium: Acrylique, encre photoluminescente, sel, collage sur toile, 3D Mixed Media, surface textur\u00e9e \u00e0 la main, technique INK3D Rebel<\/p>\n<p style=\"text-align: left;\">Type d\u2019\u0153uvre: Diptyque<\/p>\n<p style=\"text-align: left;\">Dimensions des toiles:<br \/>120 \u00d7 100 \u00d7 4,5 cm (H \u00d7 W \u00d7 D)<br \/>47.2 \u00d7 39.4 \u00d7 1.8 in<br \/>120 \u00d7 80 \u00d7 4,5 cm (H \u00d7 W \u00d7 D)<br \/>47.2 \u00d7 31.5 \u00d7 1.8 in<\/p>\n<p style=\"text-align: left;\">Dimensions totales (incluant l\u2019interstice et le d\u00e9passement):<br \/>120 \u00d7 208 \u00d7 11 cm (H \u00d7 L \u00d7 P)<br \/>47.2 \u00d7 81.9 \u00d7 4.3 in<\/p>\n<p style=\"text-align: left;\">Particularit\u00e9s : Original, pi\u00e8ce unique. Texture r\u00e9alis\u00e9e \u00e0 la main. Composition \u00e0 double spectre \u2014 transformation visible entre le jour et la nuit ; les \u00e9l\u00e9ments photoluminescents s\u2019activent dans l\u2019obscurit\u00e9.  <\/p>\n<p style=\"text-align: left;\">DESCRIPTION<\/p>\n<p style=\"text-align: left;\"><span>PAGE ZERO est plus qu\u2019une image.<\/span><\/p>\n<p style=\"text-align: left;\">C\u2019est un point z\u00e9ro.<\/p>\n<p style=\"text-align: left;\">Deux toiles blanches se tiennent dans une tension pr\u00e9cise. Entre elles s\u2019ouvre un espace vertical. Le jour, il appara\u00eet comme un canal de lumi\u00e8re. La nuit, il s\u2019active et devient la forme visible d\u2019une id\u00e9e.   <\/p>\n<p style=\"text-align: left;\">La toile de gauche d\u00e9crit la concentration comme un mouvement. Les particules de sel se condensent vers le centre. Ce qui semble d\u2019abord \u00eatre une dispersion se r\u00e9v\u00e8le comme une direction. La possibilit\u00e9 devient focalisation.   <\/p>\n<p style=\"text-align: left;\">Au centre se tient GEN.ES.IS.<\/p>\n<p style=\"text-align: left;\">Non pas comme un texte, mais comme une mise en place architecturale.<\/p>\n<p style=\"text-align: left;\">genesis \u2014 origine<\/p>\n<p style=\"text-align: left;\">gene \u2014 structure<\/p>\n<p style=\"text-align: left;\">es \u2014 essence<\/p>\n<p style=\"text-align: left;\">is \u2014 \u00eatre<\/p>\n<p style=\"text-align: left;\">GEN.ES.IS ne d\u00e9crit pas un \u00e9tat. Il d\u00e9crit la transition entre la possibilit\u00e9 et la clart\u00e9. <\/p>\n<p style=\"text-align: left;\">Depuis cette origine, une fine ligne horizontale se prolonge sur la toile de droite. Elle commence au centre et d\u00e9passe les limites de l\u2019\u0153uvre. La pens\u00e9e ne reste pas enferm\u00e9e dans l\u2019\u0153uvre. Elle va au-del\u00e0.   <\/p>\n<p style=\"text-align: left;\">La toile de droite demeure r\u00e9duite \u00e0 l\u2019essentiel. Aucune repr\u00e9sentation. Aucune illustration. Seulement une manifestation.   <\/p>\n<p style=\"text-align: left;\">Artwork Status<\/p>\n<p style=\"text-align: left;\">PAGE ZERO marque l\u2019origine conceptuelle du syst\u00e8me K-NY. Il ne montre pas le r\u00e9sultat, mais l\u2019instant qui le pr\u00e9c\u00e8de. <\/p>\n<p style=\"text-align: left;\">PAGE ZERO appartient au Cluster FOCUS &#038; STRENGTH, tout en restant en dehors d\u2019une logique de s\u00e9rie conventionnelle.<\/p>\n<p style=\"text-align: left;\">Original. Pi\u00e8ce unique. <\/p>\n<p style=\"text-align: left;\">Sign\u00e9e sur le c\u00f4t\u00e9 et au revers.<\/p>\n<p style=\"text-align: left;\">Certificat d\u2019authenticit\u00e9 inclus.<\/p>\n<p style=\"text-align: left;\">Disponibilit\u00e9: Prix sur demande.<\/p>\n<p style=\"text-align: left;\">FOCUS &#038; STRENGTH \u2014 \u0152uvre n\u00b0 2 sur 5.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||7px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span>WITHIN THE SYSTEM<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Pour les collections qui reconnaissent l\u2019origine comme la forme la plus \u00e9lev\u00e9e de pr\u00e9sence.<br \/>Non pas une image \u2014 mais le point o\u00f9 tout commence.<br \/>Une affirmation de fondation conceptuelle absolue.[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Disponible pour placement institutionnel et priv\u00e9..<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||7px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_4,3_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]Cette \u0153uvre est l\u2019origine.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Autres niveaux de PAGE ZERO :<\/p>\n<p><a href=\"https:\/\/k-ny.art\/fr\/beyond-the-canvas-page-zero\/\">Beyond the Canvas \u2192<\/a><br \/><a href=\"https:\/\/k-ny.art\/fr\/page-zero-origin-of-the-k-ny-system\/\">Origin of the K-NY system \u2192<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><span>Mat\u00e9riau &#038; Processus<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb18px|auto||auto||\u00a0\u00bb custom_padding=\u00a0\u00bb||14px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_gallery gallery_ids=\u00a0\u00bb14777,14778,14779,14780,171,169&Prime; show_title_and_caption=\u00a0\u00bboff\u00a0\u00bb zoom_icon_color=\u00a0\u00bb#000000&Prime; hover_icon=\u00a0\u00bb\uf592||fa||400&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>NAVIGATION DANS LE SYST\u00c8ME<\/p>\n<p>Cluster<br \/><a href=\"https:\/\/k-ny.art\/fr\/ensemble-focus-strength\/\">FOCUS &#038; STRENGTH<\/a><\/p>\n<p>Masterpieces<br \/><a href=\"https:\/\/k-ny.art\/fr\/masterpieces\/\">The architectural points of the K-NY system<\/a><\/p>\n<p>Syst\u00e8me lumineux<br \/><a href=\"https:\/\/k-ny.art\/fr\/double-reality\/\">DOUBLE REALITY\u2122<\/a><\/p>\n<p>Acc\u00e8s professionnel<br \/><a href=\"https:\/\/k-ny.art\/fr\/system-adc\/\">SYSTEM ADC<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bbhttps:\/\/k-ny.art\/inquiry\/\u00a0\u00bb button_text=\u00a0\u00bbDemande d\u2019\u0153uvre\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb15px\u00a0\u00bb button_text_color=\u00a0\u00bb#8F8F8F\u00a0\u00bb button_bg_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb button_border_width=\u00a0\u00bb1px\u00a0\u00bb button_border_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_font=\u00a0\u00bb||||||||\u00a0\u00bb button_use_icon=\u00a0\u00bboff\u00a0\u00bb animation_style=\u00a0\u00bbslide\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset3&Prime; box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.04)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Pour les collectionneurs avec attitude.<br \/>Acc\u00e8s priv\u00e9 au K-NY Collector Area.<br \/><a href=\"https:\/\/k-ny.art\/collector\/\" style=\"color: #999999;\">\u2192 Acc\u00e8s collectionneur<span style=\"color: #999999;\"><\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h4>AUTHENTICITY &#038; ARCHIVING<\/h4>\n<p>\nChaque \u0153uvre est une pi\u00e8ce unique et fait partie d\u2019un Cluster \u2014 une s\u00e9rie ferm\u00e9e de cinq \u0153uvres.\n<\/p>\n<p>\nToutes les \u0153uvres ont \u00e9t\u00e9 personnellement sign\u00e9es, num\u00e9rot\u00e9es et dot\u00e9es d\u2019un code officiel K-NY par Ki\u00e9ra Nagy (K-NY).\n<\/p>\n<p>\nChaque \u0153uvre est enregistr\u00e9e dans les archives K-NY et accompagn\u00e9e d\u2019un certificat d\u2019authenticit\u00e9.\n<\/p>\n<p>\nLes reproductions ou \u00e9ditions n\u2019existent pas.\n<\/p>\n<p>\nK-NY ne produit pas \u2014 il publie.\n<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p>Copyright<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label<br data-start=\"489\" data-end=\"492\"\/>All rights reserved.<br data-start=\"512\" data-end=\"515\"\/>Toutes les \u0153uvres et contenus de ce site \u2014 y compris les images, textes et mises en page \u2014 sont prot\u00e9g\u00e9s par le droit d\u2019auteur.<br data-start=\"625\" data-end=\"628\"\/>Toute reproduction, distribution ou modification sans autorisation \u00e9crite pr\u00e9alable de l\u2019artiste est interdite.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conceptual Rebellion\u2122 \u2014 art that thinks in light and speaks in the dark.The light is not an effect.It is meaning. &nbsp; PAGE ZERO &nbsp;L&rsquo;origine n&rsquo;est pas un motif.C&rsquo;est un moment.Cette \u0153uvre ne montre pas une origine.Elle la cr\u00e9e.Deux surfaces.Une ouverture.Une ligne.Ce qui est forme le jour,devient origine la nuit.The moment before everything. La lumi\u00e8re n\u2019est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-14366","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAGE ZERO \u2014 Masterpiece I \/ K-NY<\/title>\n<meta name=\"description\" content=\"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS &amp; STRENGTH.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-ny.art\/fr\/page-zero\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAGE ZERO \u2014 Masterpiece I \/ K-NY\" \/>\n<meta property=\"og:description\" content=\"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS &amp; STRENGTH.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-ny.art\/fr\/page-zero\/\" \/>\n<meta property=\"og:site_name\" content=\"k-ny.art\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T23:10:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/fr\\\/page-zero\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/fr\\\/page-zero\\\/\",\"name\":\"PAGE ZERO \u2014 Masterpiece I \\\/ K-NY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\"},\"datePublished\":\"2025-12-19T09:50:03+00:00\",\"dateModified\":\"2026-07-03T23:10:25+00:00\",\"description\":\"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS & STRENGTH.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/fr\\\/page-zero\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-ny.art\\\/fr\\\/page-zero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/fr\\\/page-zero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-ny.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAGE ZERO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"name\":\"k-ny.art\",\"description\":\"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-ny.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\",\"name\":\"k-ny.art\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"contentUrl\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"width\":2346,\"height\":1644,\"caption\":\"k-ny.art\"},\"image\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAGE ZERO \u2014 Masterpiece I \/ K-NY","description":"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS & STRENGTH.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-ny.art\/fr\/page-zero\/","og_locale":"fr_FR","og_type":"article","og_title":"PAGE ZERO \u2014 Masterpiece I \/ K-NY","og_description":"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS & STRENGTH.","og_url":"https:\/\/k-ny.art\/fr\/page-zero\/","og_site_name":"k-ny.art","article_modified_time":"2026-07-03T23:10:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-ny.art\/fr\/page-zero\/","url":"https:\/\/k-ny.art\/fr\/page-zero\/","name":"PAGE ZERO \u2014 Masterpiece I \/ K-NY","isPartOf":{"@id":"https:\/\/k-ny.art\/#website"},"datePublished":"2025-12-19T09:50:03+00:00","dateModified":"2026-07-03T23:10:25+00:00","description":"PAGE ZERO is the conceptual Masterpiece of K-NY \u2014 a diptych that marks the origin of the system and defines focus and light as structure. Developed within FOCUS & STRENGTH.","breadcrumb":{"@id":"https:\/\/k-ny.art\/fr\/page-zero\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-ny.art\/fr\/page-zero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-ny.art\/fr\/page-zero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-ny.art\/"},{"@type":"ListItem","position":2,"name":"PAGE ZERO"}]},{"@type":"WebSite","@id":"https:\/\/k-ny.art\/#website","url":"https:\/\/k-ny.art\/","name":"k-ny.art","description":"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.","publisher":{"@id":"https:\/\/k-ny.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-ny.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/k-ny.art\/#organization","name":"k-ny.art","url":"https:\/\/k-ny.art\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/","url":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","contentUrl":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","width":2346,"height":1644,"caption":"k-ny.art"},"image":{"@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/pages\/14366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/comments?post=14366"}],"version-history":[{"count":103,"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/pages\/14366\/revisions"}],"predecessor-version":[{"id":40088,"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/pages\/14366\/revisions\/40088"}],"wp:attachment":[{"href":"https:\/\/k-ny.art\/fr\/wp-json\/wp\/v2\/media?parent=14366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}