{"id":15583,"date":"2025-08-02T18:41:57","date_gmt":"2025-08-02T16:41:57","guid":{"rendered":"https:\/\/k-ny.art\/break-free\/"},"modified":"2026-07-05T13:19:05","modified_gmt":"2026-07-05T11:19:05","slug":"break-free","status":"publish","type":"page","link":"https:\/\/k-ny.art\/it\/break-free\/","title":{"rendered":"BREAK FREE"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Work&#8221; _builder_version=&#8221;4.27.6&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;0px||1px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/07\/BF-1-scaled.jpg&#8221; alt=&#8221;BREAK FREE by K-NY \u2014 photoluminescent conceptual artwork in spatial context, dual-spectrum composition interacting with light and architecture.&#8221; title_text=&#8221;BREAK FREE \u2014 spatial installation view&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||44px|||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: right;\"><span class=\"Apple-converted-space\">Conceptual Rebellion\u2122 \u2014 <\/span><br \/>arte che pensa nella luce e parla nell\u2019oscurit\u00e0.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p data-start=\"641\" data-end=\"685\" style=\"text-align: right;\">The light is not an effect.<br data-start=\"668\" data-end=\"671\"\/>It is meaning.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|&#8211;et_global_heading_font_weight||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_3_font_size_phone=&#8221;10px&#8221; header_3_font_size_last_edited=&#8221;off|desktop&#8221; module_alignment_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>ARTWORK<\/h3>\n<h2>BREAK FREE<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La libert\u00e0 inizia dove il controllo diventa arte.<\/p>\n<p>Break Free non \u00e8 una partenza \u2014 \u00e8 una rottura del sistema.<br \/>Oro, carbone, crypto \u2014 energia in tre stati:<br \/>Valore. Tensione. Consapevolezza.  <\/p>\n<p>Tra FOCUS e FREE si innalza la curva della volont\u00e0. Un toro dorato attraversa l\u2019oscurit\u00e0 \u2014 simbolo di movimento, ascesa e forza consapevole. <\/p>\n<p>La brillantezza non \u00e8 lusso \u2014 \u00e8 intenzione.<\/p>\n<p>Di giorno: struttura, pressione e presenza.<br \/>Di notte: una luce fatta di movimento e significato.<\/p>\n<p>L\u2019opera esplora la crescita non come possesso, ma come forma di consapevolezza.<br \/>Break Free ricorda che la libert\u00e0 non \u00e8 una condizione \u2014 ma una decisione.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/09\/K-NY-BREAK-FREE-new1.jpg&#8221; title_text=&#8221;Screenshot&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;59px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h5 style=\"text-align: center;\">Ci\u00f2 che la rende unica: la fotoluminescenza integrata trasforma ogni opera nel corso della giornata.<\/h5>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/K-NY-Break-Free-Day.jpeg&#8221; title_text=&#8221;K-NY Break Free Day&#8221; show_in_lightbox=&#8221;on&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; border_width_all=&#8221;20px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;30px&#8221; border_width_all__hover_enabled=&#8221;on&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;134%|134%&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Di giorno<\/b><\/p>\n<p>arte 3D potente, in pieno colore e forma<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/01\/BREAK-FREE-evening-2.jpeg&#8221; alt=&#8221;K-NY artwork BREAK FREE \u2013 photoluminescent acrylic urban luxury art&#8221; title_text=&#8221;Opera K-NY BREAK FREE \u2014 sera&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; border_width_all=&#8221;20px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover_enabled=&#8221;on&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;30px&#8221; border_width_all__hover_enabled=&#8221;on&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;134%|134%&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Al calare della sera<\/b><\/p>\n<p>sottili accenti luminosi spostano la percezione<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/01\/BREAK-FREE-night-2.jpeg&#8221; alt=&#8221;K-NY artwork BREAK FREE \u2013 photoluminescent acrylic urban luxury art&#8221; title_text=&#8221;BREAK FREE night&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; border_width_all=&#8221;20px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; box_shadow_color__hover_enabled=&#8221;on&#8221; border_width_all__hover=&#8221;30px&#8221; border_width_all__hover_enabled=&#8221;on&#8221; transform_styles__hover_enabled=&#8221;on|hover&#8221; transform_scale__hover_enabled=&#8221;on|hover&#8221; transform_translate__hover_enabled=&#8221;on|desktop&#8221; transform_rotate__hover_enabled=&#8221;on|desktop&#8221; transform_skew__hover_enabled=&#8221;on|desktop&#8221; transform_origin__hover_enabled=&#8221;on|desktop&#8221; transform_scale__hover=&#8221;134%|134%&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_3_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><b>Di notte<\/b><\/p>\n<p>il messaggio centrale si illumina \u2014 ridotto all\u2019essenziale, intensamente tangibile<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/B_cutout_white-Q.png&#8221; title_text=&#8221;K-NY Break Free Day&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/K-NY-Break-Free-Day.jpeg&#8221; parallax=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/CC.png&#8221; title_text=&#8221;CC&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;140px&#8221; max_width_tablet=&#8221;70px&#8221; max_width_phone=&#8221;35px&#8221; max_width_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;003e9429-8e11-4d9e-968b-8881092bbf81&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;48px&#8221; header_2_line_height=&#8221;1.1em&#8221; custom_margin=&#8221;||0px||false|false&#8221; header_2_font_size_tablet=&#8221;32px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_line_height_tablet=&#8221;1.2em&#8221; header_2_line_height_phone=&#8221;&#8221; header_2_line_height_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><strong><\/strong><\/h1>\n<h1><strong><\/strong><\/h1>\n<h1><strong>Focus is the new currency. <\/strong><\/h1>\n<h1><b><\/b><\/h1>\n<h1><b>Freedom is the return.<\/b><\/h1>\n<h1><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.7&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_phone=&#8221;10px&#8221; header_3_font_size_last_edited=&#8221;off|desktop&#8221; module_alignment_last_edited=&#8221;off|desktop&#8221; text_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<\/p>\n<h1 style=\"text-align: left;\">BREAK FREE<\/h1>\n<p style=\"text-align: left;\">Titolo: BREAK FREE, parte della INK3D Rebel Series<br \/>Cluster: POWER &#038; FREEDOM (opera n. 1 di 5)<br \/>Anno: 2025<br \/>Tecnica: acrilico, inchiostro fotoluminescente, collage su tela, tecnica mista 3D, superficie texturizzata a mano, tecnica INK3D Rebel<\/p>\n<p style=\"text-align: left;\">Dimensioni della tela:<br \/>100 \u00d7 100 \u00d7 4,5 cm (altezza \u00d7 larghezza \u00d7 profondit\u00e0)<br \/>40 \u00d7 40 \u00d7 1.8 in (altezza \u00d7 larghezza \u00d7 profondit\u00e0)<\/p>\n<p style=\"text-align: left;\">Dimensioni dell&#8217;opera:<br \/>103 \u00d7 100 \u00d7 10 cm (Altezza \u00d7 Larghezza \u00d7 Profondit\u00e0)<br \/>40,6 \u00d7 39,4 \u00d7 3,9 in (Altezza \u00d7 Larghezza \u00d7 Profondit\u00e0)<\/p>\n<p style=\"text-align: left;\">Caratteristiche speciali: opera originale e unica. Superficie realizzata a mano. Composizione a doppio spettro \u2014 trasformazione visibile tra giorno e notte; elementi fotoluminescenti attivi nell\u2019oscurit\u00e0. Arricchita con foglia oro imitazione e autentica foglia d\u2019oro 23 carati. Integra rappresentazioni di valute globali, lingotti d\u2019oro e vere monete di criptovaluta (BTC, ETH, DOGE, LTC, EOS), inclusi elementi in carbone.   <\/p>\n<p style=\"text-align: left;\">Descrizione<br \/>BREAK FREE \u00e8 pi\u00f9 di un dipinto \u2014 \u00e8 un manifesto visivo di forza, indipendenza e del coraggio di oltrepassare i limiti imposti.<br \/>L\u2019opera unisce acrilico, inchiostro fotoluminescente, collage, carbone, foglia d\u2019oro artistica e, in prevalenza, autentica foglia d\u2019oro 23 carati con monete originali di criptovaluta. Ogni materiale risponde a un\u2019intenzione: la brillantezza dell\u2019oro simboleggia valore e sovranit\u00e0, mentre il carbone introduce un duplice significato ironico. In tedesco \u201cKohle\u201d significa sia carbone sia denaro \u2014 un sottile gioco linguistico che collega energia, economia e potere creativo.  <\/p>\n<p style=\"text-align: left;\">Nella parte inferiore della composizione, l\u2019iscrizione dorata BREAK FREE irradia energia. Al di sopra, la parola tridimensionale FOCUS afferma la precisione, mentre la sezione superiore \u00e8 coronata da FREE. Una curva ascendente di mercato, tracciata in carbone, guida lo sguardo verso l\u2019alto \u2014 fino all\u2019iconico Charging Bull dorato, emblema senza tempo di crescita e determinazione.  <\/p>\n<p style=\"text-align: left;\">Di giorno, gli elementi in oro e collage esprimono valore tangibile e tensione materiale. Di notte, i dettagli fotoluminescenti si risvegliano: la curva inizia a brillare, le linee si attivano e l\u2019opera si trasforma in una seconda dimensione luminosa. <\/p>\n<p style=\"text-align: left;\">BREAK FREE interpreta la libert\u00e0 non come fuga, ma come direzione consapevole. L\u2019opera esplora crescita, valore e ambizione come forze psicologiche modellate da disciplina, consapevolezza e intenzione. <\/p>\n<p style=\"text-align: left;\">La composizione bilancia ricchezza materiale e tensione percettiva \u2014 trasformando simboli di finanza, potere e movimento in una riflessione sull\u2019indipendenza stessa.<\/p>\n<p style=\"text-align: left;\">COLLECTOR VERSION<br \/>Un\u2019opera per coloro che vedono oltre la superficie.<\/p>\n<p style=\"text-align: left;\">BREAK FREE interpreta la libert\u00e0 come precisione \u2014 non come fuga, ma come intenzione.<\/p>\n<p style=\"text-align: left;\">Per collezionisti che apprezzano la disciplina quanto l\u2019indipendenza.<\/p>\n<p style=\"text-align: left;\">Firma: logo sul fronte, firmato sul lato e sul retro. Certificato di autenticit\u00e0 incluso.<br \/>Disponibilit\u00e0: Originale.<br \/>Status del cluster: POWER &#038; FREEDOM \u2013 Work No. 1 of 5.<br \/>Prezzo su richiesta. <\/p>\n<p style=\"text-align: left;\">Pezzo unico, firmato e certificato.<\/p>\n<p style=\"text-align: left;\">Il valore nasce da percezione, rarit\u00e0 e precisione concettuale \u2014 non dalla dimensione.<\/p>\n<p style=\"text-align: left;\">Un K-NY non si misura \u2014 si vive.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>WITHIN THE SYSTEM<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Per collezionisti che riconoscono il momento in cui inizia l\u2019indipendenza.<br \/>Non un atto di fuga \u2014 ma uno spostamento di autorit\u00e0.<br \/>Una dichiarazione di potere autodeterminato in una collezione.[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Disponibile per collocazione istituzionale e privata.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Quest\u2019opera segna l\u2019impulso.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/k-ny.art\/it\/masterpieces\/\">Masterpieces<\/a><br \/><a href=\"https:\/\/k-ny.art\/it\/cluster\/\">\u2192 System<\/a><br \/><a href=\"https:\/\/k-ny.art\/it\/contatti\/\">\u2192 Studio<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dettagli &#038; Ispirazione<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;18px|auto||auto||&#8221; custom_padding=&#8221;||14px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;41127,41128,41129,41130,41131,41132,41133,41134,41135,41136,41137,41138,41139,15576,41140,15581,41141,15577,15580,41120,169,171&#8243; show_title_and_caption=&#8221;off&#8221; zoom_icon_color=&#8221;#000000&#8243; hover_icon=&#8221;\uf592||fa||400&#8243; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>Beyond the Canvas<\/h4>\n<p>In BREAK FREE la tensione diventa tangibile \u2014 un\u2019impennata, un grido contro la costrizione.<br \/>Su una superficie nera profonda, attraversata dal carbone, brillantezza, texture e luminosit\u00e0 si scontrano in un\u2019esplosione di energia controllata.<\/p>\n<p>L\u2019uso del carbone porta con s\u00e9 un\u2019ironia deliberata: rappresenta il mezzo artistico classico \u2014 e, in tedesco, il \u201cdenaro\u201d.<br \/>Questa dualit\u00e0 costituisce il nucleo intellettuale dell\u2019opera \u2014 una riflessione sul valore, sulla dipendenza e sulla complessa tensione tra arte ed economia.<\/p>\n<p>Da questa base si eleva un messaggio in oro: BREAK FREE \u2014 un richiamo alla liberazione.<br \/>Al di sopra, la parola tridimensionale FOCUS impone la propria presenza; in alto, quasi trascendente, appare FREE \u2014 come obiettivo, come promessa.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p> Una curva di mercato in forte ascesa, tracciata in carbone, si illumina nell\u2019oscurit\u00e0 \u2014 una storia di crescita e determinazione.<br \/>Il Charging Bull dorato attraversa la composizione come emblema di uno slancio inarrestabile.<\/p>\n<p>Eppure BREAK FREE \u00e8 pi\u00f9 di un simbolo.<br \/>Autentiche monete di criptovaluta, raffigurazioni di valute, vero oro a 23 carati, oro artistico e strutture realizzate a mano si fondono in un\u2019opera che unisce valore materiale e libert\u00e0 intellettuale.<br \/>Di giorno irradia chiarezza, di notte si trasforma \u2014 luminosa, viva, indomita.<\/p>\n<p>BREAK FREE \u00e8 insieme manifesto e specchio \u2014 una creazione per chi non si limita a collezionare, ma sente;<br \/>per chi si libera da limitazioni, invidia e convenzioni<br \/>e trova nell\u2019arte non una decorazione, ma il riflesso della propria sovranit\u00e0 interiore.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||7px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/k-ny.art\/inquiry\/&#8221; button_text=&#8221;Richiesta opera&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#8F8F8F&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;#8F8F8F&#8221; button_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; button_use_icon=&#8221;off&#8221; animation_style=&#8221;slide&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Per collezionisti con carattere.<br \/>Accesso privato all\u2019area collezionisti K-NY su richiesta.<br \/><span style=\"color: #999999;\"><a href=\"https:\/\/k-ny.art\/collector\/\" style=\"color: #999999;\">\u2192 Collector Access<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">Questa opera fa parte di un Cluster esclusivo. Scopri tutte e 5 le opere della serie chiusa. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/k-ny.art\/it\/cluster-power-freedom\/&#8221; button_text=&#8221;Vai al Cluster&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#8F8F8F&#8221; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;#8F8F8F&#8221; button_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; button_icon=&#8221;&#x24;||divi||400&#8243; animation_style=&#8221;slide&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;20px|||||&#8221; custom_padding=&#8221;25px||13px|||&#8221; global_module=&#8221;986&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>AUTHENTICITY &#038; ARCHIVING<\/h4>\n<p>Ogni opera \u00e8 un pezzo unico e parte di un Cluster \u2014 una serie chiusa di cinque opere.<\/p>\n<p>Tutte le opere sono state firmate personalmente, numerate e assegnate a un codice ufficiale K-NY da Ki\u00e9ra Nagy (K-NY).<\/p>\n<p>Ogni opera \u00e8 registrata all\u2019interno dell\u2019Archivio K-NY ed \u00e8 accompagnata da un Certificato di Autenticit\u00e0.<\/p>\n<p>Non esistono riproduzioni n\u00e9 edizioni.<\/p>\n<p>K-NY non produce \u2014 pubblica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;14px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4 style=\"text-align: left;\">Night Colors. Illumination in the Dark. <b><\/b><\/h4>\n<p>K-NY non scompare nella notte.<br \/>Si trasforma.<\/p>\n<p>Quando la luce svanisce, un altro livello dell\u2019opera inizia a emergere.<br \/>Caricati dalla luce del giorno, dalla luce artificiale o dalla luce nera, gli elementi fotoluminescenti attivano la superficie e spostano la percezione dell\u2019opera.<\/p>\n<p>Ci\u00f2 che di giorno appare controllato e silenzioso pu\u00f2 diventare luminoso, instabile o psicologicamente carico nell\u2019oscurit\u00e0.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">L\u2019opera non esiste pi\u00f9 come immagine fissa.<br \/>Inizia a operare attraverso trasformazione, memoria e percezione.<\/p>\n<p>La luce non viene utilizzata come effetto.<br \/>Funziona come struttura, attivazione e linguaggio.<\/p>\n<p>La notte non ripete l\u2019opera.<br \/>Rivela un altro stato di essa..[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.27.4&#8243; max_width=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/04\/K-NY-Artwork-ZERO-IN-scaled.jpeg&#8221; alt=&#8221;K-NY artwork ZERO IN \u2013 focused luminous acrylic art from the FOCUS &amp; STRENGTH cluster&#8221; title_text=&#8221;K-NY Artwork ZERO IN&#8221; url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; _builder_version=&#8221;4.27.6&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;custom&#8221; background_image_width=&#8221;40%&#8221; background_position=&#8221;bottom_left&#8221; max_width=&#8221;800px&#8221; max_width_tablet=&#8221;560px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;||40px|78px||&#8221; custom_padding_tablet=&#8221;40px|30px|0px|0px&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|desktop&#8221; background_position_tablet=&#8221;top_right&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.2)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Opere disponibili&#8221; button_url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; button_text=&#8221;Non per tutti \u2014 scopri perch\u00e9.&#8221; _builder_version=&#8221;4.27.6&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_bg_color_gradient_stops=&#8221;#ffffff 90%|#000000 100%&#8221; button_bg_color_gradient_start=&#8221;#ffffff&#8221; button_bg_color_gradient_start_position=&#8221;90%&#8221; button_bg_color_gradient_end=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; button_custom_padding=&#8221;|0px||0px||true&#8221; transform_scale_tablet=&#8221;&#8221; transform_scale_phone=&#8221;&#8221; transform_scale_last_edited=&#8221;on|desktop&#8221; transform_translate=&#8221;-120px|40px&#8221; transform_translate_tablet=&#8221;0px|0px&#8221; transform_translate_phone=&#8221;&#8221; transform_translate_last_edited=&#8221;on|phone&#8221; transform_translate_linked=&#8221;off&#8221; transform_rotate_tablet=&#8221;&#8221; transform_rotate_phone=&#8221;&#8221; transform_rotate_last_edited=&#8221;on|desktop&#8221; transform_skew_tablet=&#8221;&#8221; transform_skew_phone=&#8221;&#8221; transform_skew_last_edited=&#8221;on|desktop&#8221; transform_origin_tablet=&#8221;&#8221; transform_origin_phone=&#8221;&#8221; transform_origin_last_edited=&#8221;on|desktop&#8221; transform_styles_last_edited=&#8221;on|phone&#8221; text_orientation=&#8221;left&#8221; background_layout=&#8221;light&#8221; custom_margin_tablet=&#8221;||-60px|&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; link_option_url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; transform_styles_tablet=&#8221;&#8221; transform_styles_phone=&#8221;&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; box_shadow_style_button=&#8221;preset2&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;1px&#8221; box_shadow_blur_button=&#8221;0px&#8221; box_shadow_color_button=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Selezionate.<br \/>Mai ripetute.<\/p>\n<p>Ogni opera \u00e8 una dichiarazione autonoma: fisica, luminosa, assoluta.<\/p>\n<p>La percezione apre spazi emotivi.<\/p>\n<p>Non si sceglie un K-NY.<br \/>\u00c8 lui a scegliere te.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.27.4&#8243; max_width=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/05\/FOCUS-STRENGTH-\u2014-K-NY-Cluster-Icon.png&#8221; alt=&#8221;Glowing circular light structure representing the K-NY cluster FOCUS &amp; STRENGTH \u2014 controlled energy flow, precision, and perceptual stability within the K-NY system.&#8221; title_text=&#8221;FOCUS &amp; STRENGTH \u2014 K-NY Cluster Icon&#8221; url=&#8221;https:\/\/k-ny.art\/it\/cluster\/&#8221; _builder_version=&#8221;4.27.6&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;custom&#8221; background_image_width=&#8221;40%&#8221; background_position=&#8221;bottom_left&#8221; max_width=&#8221;800px&#8221; max_width_tablet=&#8221;560px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;||40px|78px||&#8221; custom_padding_tablet=&#8221;40px|30px|0px|0px&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|desktop&#8221; background_position_tablet=&#8221;top_right&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.2)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Cluster&#8221; button_url=&#8221;https:\/\/k-ny.art\/it\/cluster\/&#8221; button_text=&#8221;Solo coloro che sono all\u2019interno ne diventano parte.&#8221; _builder_version=&#8221;4.27.6&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_bg_color_gradient_stops=&#8221;#ffffff 90%|#000000 100%&#8221; button_bg_color_gradient_start=&#8221;#ffffff&#8221; button_bg_color_gradient_start_position=&#8221;90%&#8221; button_bg_color_gradient_end=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; button_custom_padding=&#8221;|0px||0px||true&#8221; transform_scale_tablet=&#8221;&#8221; transform_scale_phone=&#8221;&#8221; transform_scale_last_edited=&#8221;on|desktop&#8221; transform_translate=&#8221;-120px|40px&#8221; transform_translate_tablet=&#8221;0px|0px&#8221; transform_translate_phone=&#8221;&#8221; transform_translate_last_edited=&#8221;on|phone&#8221; transform_translate_linked=&#8221;off&#8221; transform_rotate_tablet=&#8221;&#8221; transform_rotate_phone=&#8221;&#8221; transform_rotate_last_edited=&#8221;on|desktop&#8221; transform_skew_tablet=&#8221;&#8221; transform_skew_phone=&#8221;&#8221; transform_skew_last_edited=&#8221;on|desktop&#8221; transform_origin_tablet=&#8221;&#8221; transform_origin_phone=&#8221;&#8221; transform_origin_last_edited=&#8221;on|desktop&#8221; transform_styles_last_edited=&#8221;on|phone&#8221; text_orientation=&#8221;left&#8221; background_layout=&#8221;light&#8221; custom_margin_tablet=&#8221;||-60px|&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; link_option_url=&#8221;https:\/\/k-ny.art\/it\/cluster\/&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; transform_styles_tablet=&#8221;&#8221; transform_styles_phone=&#8221;&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; box_shadow_style_button=&#8221;preset2&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;1px&#8221; box_shadow_blur_button=&#8221;0px&#8221; box_shadow_color_button=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>K-NY non lavora in serie.<br \/>Ogni Cluster \u00e8 un sistema artistico chiuso \u2014 cinque opere, un\u2019idea, un campo di tensione. <\/p>\n<p>Una volta completato, un Cluster rimane sigillato.<br \/>Nessuna aggiunta. Nessuna modifica. Nessun ritorno.   <\/p>\n<p>Un Cluster non \u00e8 una collezione.<br \/>\u00c8 un manifesto in frammenti. <\/p>\n<p>Cinque prospettive. Una struttura. <\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat-y&#8221; min_height=&#8221;554.4px&#8221; custom_margin=&#8221;||29px|||&#8221; custom_padding=&#8221;0px|||||&#8221; global_module=&#8221;697&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]In K-NY, l\u2019irritazione non \u00e8 mai un incidente.<br \/>Segna il momento in cui il pensiero rifiuta l\u2019obbedienza.<\/p>\n<p>K-NY rappresenta lusso con intelligenza.<br \/>E un cenno luminoso.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>COLLECTOR POSITIONING (2026)<br \/>K-NY definisce il valore attraverso rarit\u00e0, percezione e rilevanza sistemica.<br \/>Ogni opera \u00e8 unica, firmata, certificata e posizionata all\u2019interno di un\u2019architettura di cluster chiusa.<br \/>Le opere pubblicate formano il livello visibile del sistema.<br \/>Altre esistono esclusivamente come Private Release, Vaulted Work o assenza controllata.<br \/>Prezzo su richiesta.<br \/>K-NY non produce \u2014 pubblica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_menu menu_style=&#8221;centered&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_menu][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.27.4&#8243; border_width_top=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Copyright<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label<br \/>Tutti i diritti riservati.<br \/>Tutte le opere e i contenuti di questo sito web \u2014 incluse immagini, testi e layout \u2014 sono protetti da diritto d\u2019autore. Qualsiasi riproduzione, distribuzione o modifica senza previo consenso scritto dell\u2019artista \u00e8 vietata. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;20px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">K-NY <\/span><span style=\"color: #808080;\">PARLA DIRETTAMENTE.<\/span><\/strong><\/p>\n<p>Nessun intermediario. Nessun filtro.<br \/>Se un\u2019opera ha catturato la tua attenzione,<br \/>d\u00ec quale \u2014 e perch\u00e9.<br \/>Il dialogo inizia solo<br \/>quando l\u2019intenzione \u00e8 chiara. <\/p>\n<h3><b><\/b><\/h3>\n<p><strong><span style=\"color: #808080;\">STUDIO (Europe)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/k-ny.art\/it\/contatti\/\">Visita la pagina Contatti <span>\u2192<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">INDIRIZZO<\/span><\/strong><\/p>\n<p>K-NY Studio \u2013 Ufficio<br \/>Ki\u00e9ra Nagy<br \/>Koendgenstr. 3<br \/>45131 Essen, Germania<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><br \/>ORARI DI APERTURA<\/span><\/strong><\/p>\n<p>Visite in studio solo su appuntamento..<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">INFORMAZIONI<\/span><\/strong><\/p>\n<p>I prezzi non includono IVA, spedizione e assicurazione.<br \/>Le opere originali di Ki\u00e9ra Nagy (K-NY) sono soggette all\u2019aliquota IVA ridotta del 7 % secondo la normativa fiscale tedesca (\u00a7 12 Abs. 2 Nr. 1 UStG e Allegato 2).<br \/>Per le esportazioni al di fuori dell\u2019UE l\u2019IVA non si applica.<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label \u2014<br \/>Tutti i diritti riservati.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">FOLOW<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.27.6&#8243; custom_margin=&#8221;-20px|||-10px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-20px||&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; filter_invert=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; icon_color__hover=&#8221;#e02b20&#8243;][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/kny.luxuryart\/&#8221; _builder_version=&#8221;4.27.5&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/kny.luxuryart\/&#8221; _builder_version=&#8221;4.27.6&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;http:\/\/www.linkedin.com\/in\/kiera-nagy&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_text disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Iscriviti<\/h3>\n<p>alla newsletter e sii tra i primi a scoprire nuove opere, mostre e contenuti esclusivi in anteprima.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=&#8221;SlavaET|11a914d1cc&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; form_field_background_color=&#8221;#f3f3f4&#8243; form_field_custom_padding=&#8221;12px||12px||true&#8221; header_font=&#8221;Montserrat|||on|||||&#8221; header_font_size=&#8221;14px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.8em&#8221; form_field_font=&#8221;||||||||&#8221; form_field_font_size=&#8221;14px&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; button_custom_padding=&#8221;12px||12px||true&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;-39px||&#8221; border_radii_fields=&#8221;on|0px|0px|0px|0px&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_signup][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Le opere K-NY sono pubblicate in sistemi chiusi e collocate in collezioni private e istituzionali.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conceptual Rebellion\u2122 \u2014 arte che pensa nella luce e parla nell\u2019oscurit\u00e0.The light is not an effect.It is meaning.ARTWORK BREAK FREELa libert\u00e0 inizia dove il controllo diventa arte. Break Free non \u00e8 una partenza \u2014 \u00e8 una rottura del sistema.Oro, carbone, crypto \u2014 energia in tre stati:Valore. Tensione. Consapevolezza. Tra FOCUS e FREE si innalza la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-15583","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BREAK FREE \u2014 POWER &amp; FREEDOM \/ K-NY<\/title>\n<meta name=\"description\" content=\"BREAK FREE is a photoluminescent K-NY original from the POWER &amp; FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-ny.art\/it\/break-free\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BREAK FREE \u2014 POWER &amp; FREEDOM \/ K-NY\" \/>\n<meta property=\"og:description\" content=\"BREAK FREE is a photoluminescent K-NY original from the POWER &amp; FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-ny.art\/it\/break-free\/\" \/>\n<meta property=\"og:site_name\" content=\"k-ny.art\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-05T11:19:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"34 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/break-free\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/it\\\/break-free\\\/\",\"name\":\"BREAK FREE \u2014 POWER & FREEDOM \\\/ K-NY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\"},\"datePublished\":\"2025-08-02T16:41:57+00:00\",\"dateModified\":\"2026-07-05T11:19:05+00:00\",\"description\":\"BREAK FREE is a photoluminescent K-NY original from the POWER & FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/break-free\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-ny.art\\\/it\\\/break-free\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/break-free\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-ny.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BREAK FREE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"name\":\"k-ny.art\",\"description\":\"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-ny.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\",\"name\":\"k-ny.art\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"contentUrl\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"width\":2346,\"height\":1644,\"caption\":\"k-ny.art\"},\"image\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BREAK FREE \u2014 POWER & FREEDOM \/ K-NY","description":"BREAK FREE is a photoluminescent K-NY original from the POWER & FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-ny.art\/it\/break-free\/","og_locale":"it_IT","og_type":"article","og_title":"BREAK FREE \u2014 POWER & FREEDOM \/ K-NY","og_description":"BREAK FREE is a photoluminescent K-NY original from the POWER & FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.","og_url":"https:\/\/k-ny.art\/it\/break-free\/","og_site_name":"k-ny.art","article_modified_time":"2026-07-05T11:19:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"34 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-ny.art\/it\/break-free\/","url":"https:\/\/k-ny.art\/it\/break-free\/","name":"BREAK FREE \u2014 POWER & FREEDOM \/ K-NY","isPartOf":{"@id":"https:\/\/k-ny.art\/#website"},"datePublished":"2025-08-02T16:41:57+00:00","dateModified":"2026-07-05T11:19:05+00:00","description":"BREAK FREE is a photoluminescent K-NY original from the POWER & FREEDOM cluster \u2014 a work that transforms light into a statement of autonomy and release.","breadcrumb":{"@id":"https:\/\/k-ny.art\/it\/break-free\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-ny.art\/it\/break-free\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-ny.art\/it\/break-free\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-ny.art\/"},{"@type":"ListItem","position":2,"name":"BREAK FREE"}]},{"@type":"WebSite","@id":"https:\/\/k-ny.art\/#website","url":"https:\/\/k-ny.art\/","name":"k-ny.art","description":"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.","publisher":{"@id":"https:\/\/k-ny.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-ny.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/k-ny.art\/#organization","name":"k-ny.art","url":"https:\/\/k-ny.art\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/","url":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","contentUrl":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","width":2346,"height":1644,"caption":"k-ny.art"},"image":{"@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/comments?post=15583"}],"version-history":[{"count":74,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15583\/revisions"}],"predecessor-version":[{"id":41144,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15583\/revisions\/41144"}],"wp:attachment":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/media?parent=15583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}