{"id":15750,"date":"2025-09-17T17:15:35","date_gmt":"2025-09-17T15:15:35","guid":{"rendered":"https:\/\/k-ny.art\/cluster-vibes-flow\/"},"modified":"2026-07-05T11:48:31","modified_gmt":"2026-07-05T09:48:31","slug":"cluster-vibes-flow","status":"publish","type":"page","link":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/","title":{"rendered":"Cluster-VIBES-FLOW"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Work&#8221; _builder_version=&#8221;4.27.6&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; min_height=&#8221;1370.6px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_3_font_size_phone=&#8221;10px&#8221; header_3_font_size_last_edited=&#8221;off|desktop&#8221; module_alignment_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\">Cluster<\/p>\n<h2 style=\"text-align: center;\">VIBES &#038; FLOW<\/h2>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,3_5,1_5&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/05\/VIBES-FLOW-\u2014-K-NY-Cluster-Icon.jpg&#8221; alt=&#8221;Diffused glowing light ring representing the K-NY cluster VIBES &amp; FLOW \u2014 drifting energy, rhythm, movement, and fluid perception within the K-NY system.&#8221; title_text=&#8221;VIBES &amp; FLOW \u2014 K-NY Cluster Icon&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/08\/CC.png&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; width=&#8221;60%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: right;\"><b><\/b><\/h2>\n<h2 style=\"text-align: right;\"><b><\/b><\/h2>\n<h3>VIBES &#038; FLOW \u2013 Not just rhythm.<\/h3>\n<h3>Flow as a way of life<i>.<\/i><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L&#8217;energia diventa atmosfera.<br \/>Il movimento diventa libert\u00e0.<\/p>\n<p>VIBES &#038; FLOW \u00e8 un cluster chiuso composto da cinque opere.<br \/>All&#8217;interno del sistema K-NY esplora la relazione tra percezione, tempo e ritmo.<\/p>\n<p>Impulso \u2192 Espansione \u2192 Consapevolezza \u2192 Soglia \u2192 Stato<\/p>\n<p>Il flow non \u00e8 fuga.<br \/>Il ritmo diventa presenza.<br \/>L&#8217;atmosfera diventa spazio.<\/p>\n<p>Un cluster completo rimane chiuso.<br \/>Disponibilit\u00e0 e condizioni individuali su richiesta.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/07\/K-NY-Gallery-Space.51.png&#8221; title_text=&#8221;K-NY Gallery Space.&#8221; url=&#8221;https:\/\/k-ny.art\/it\/ibiza-sound\/&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; alt=&#8221;K-NY artwork in the K-NY Gallery Space, demonstrating the relationship between artwork, architecture and perception.&#8221; sticky_enabled=&#8221;0&#8243; width=&#8221;100%&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.7&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;48px||||false|false&#8221; hover_enabled=&#8221;0&#8243; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>IBIZA SOUND<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>VIBES &#038; FLOW<br \/>(Work No. 1 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg&#8221; alt=&#8221;K-NY Vault icon \u2013 curated access to unseen artworks&#8221; title_text=&#8221;K-NY Vault icon&#8221; url=&#8221;https:\/\/k-ny.art\/it\/the-vault\/&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.7&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;48px||||false|false&#8221; hover_enabled=&#8221;0&#8243; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><strong>ETERNAL VIBES OF THE ISLAND<\/strong><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>VIBES &#038; FLOW<br \/>(Work No. 2 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; custom_padding=&#8221;0px||||false|false&#8221; custom_margin=&#8221;-20px||||false|false&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg&#8221; title_text=&#8221;Screenshot&#8221; url=&#8221;https:\/\/k-ny.art\/it\/the-vault\/&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.7&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;48px||||false|false&#8221; hover_enabled=&#8221;0&#8243; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><b>MONEY MAGNET<\/b><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>VIBES &#038; FLOW<br \/>(Work No. 3 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg&#8221; alt=&#8221;K-NY Vault icon \u2013 curated access to unseen artworks&#8221; title_text=&#8221;K-NY Vault icon&#8221; url=&#8221;https:\/\/k-ny.art\/it\/the-vault\/&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;48px||||false|false&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><b>LIFE ON<\/b><\/p>\n<p style=\"text-align: left;\">Cluster:<br \/>VIBES &#038; FLOW<br \/>(Work No. 4 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-Safe-2.jpeg&#8221; alt=&#8221;K-NY Vault icon \u2013 curated access to unseen artworks&#8221; title_text=&#8221;K-NY Vault icon&#8221; url=&#8221;https:\/\/k-ny.art\/it\/the-vault\/&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.7&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;48px||||false|false&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">ARTWORK<br \/><b><\/b><strong>GOOD.<\/strong><\/p>\n<p style=\"text-align: left;\"><b><\/b>Cluster:<br \/>VIBES &#038; FLOW<br \/>(Work No. 5 of 5)<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>VAULTED<br \/>Not in circulation.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>LETTURA CURATORIALE DEL CLUSTER<\/p>\n<p>VIBES &#038; FLOW descrive la trasformazione dal movimento alla risonanza.<br \/>Le opere indagano il ritmo non come azione, ma come stato percettivo nel quale emozione, atmosfera e presenza iniziano ad allinearsi. Il flow non appare qui come accelerazione, ma come una forma di esistenza senza resistenza. Tra luce, acqua, calore, suono e apertura emotiva, il cluster costruisce una condizione in cui il tempo si dissolve nella percezione e l\u2019atmosfera diventa spazio.  <\/p>\n<p>POSIZIONE ALL\u2019INTERNO DEL SISTEMA K-NY<\/p>\n<p>All\u2019interno del sistema K-NY, VIBES &#038; FLOW definisce la relazione tra percezione e tempo. Mentre FOCUS &#038; STRENGTH stabilisce l\u2019origine attraverso la chiarezza, POWER &#038; FREEDOM manifesta la sovranit\u00e0 attraverso la direzione e IRONY &#038; EDGE costruisce distanza intellettuale, questo cluster trasforma la presenza in risonanza. Non decisione. Non controllo. Ma l\u2019esperienza della realt\u00e0 come ritmo.    <\/p>\n<p>VIBES &#038; FLOW porta il ritmo dell\u2019energia mediterranea \u2014 luce del sole, acqua, musica, calore, notte e apertura emotiva trasformati in spazio percettivo. Ibiza non \u00e8 un luogo. \u00c8 uno stile di vita.  <\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>The K-NY Collection<br \/>Un\u2019opera pubblicata rappresenta l\u2019identit\u00e0 visibile del proprio Cluster.<br \/>Incarna l\u2019attitudine, la visione e il lusso ribelle di K-NY \u2013 dove la presenza stessa diventa forma d\u2019arte.<br \/>Ogni pezzo \u00e8 scelto per essere visto, eppure rimane singolare \u2013 creato per chi comprende la differenza tra visibilit\u00e0 e sostanza.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/07\/Smartist_2DB16612-C819-40E5-AC1C-685505D41D60-scaled.jpg&#8221; alt=&#8221;K-NY artwork in the K-NY Gallery Space, demonstrating the relationship between artwork, architecture and perception.&#8221; title_text=&#8221;K-NY Gallery Space.&#8221; url=&#8221;https:\/\/k-ny.art\/it\/ibiza-sound\/&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_cta button_url=&#8221;https:\/\/k-ny.art\/it\/ibiza-sound\/&#8221; button_text=&#8221;Maggiori dettagli&#8221; _builder_version=&#8221;4.27.6&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_bg_color_gradient_stops=&#8221;#ffffff 90%|#000000 100%&#8221; button_bg_color_gradient_start=&#8221;#ffffff&#8221; button_bg_color_gradient_start_position=&#8221;90%&#8221; button_bg_color_gradient_end=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; button_custom_padding=&#8221;|0px||0px||true&#8221; transform_scale_tablet=&#8221;&#8221; transform_scale_phone=&#8221;&#8221; transform_scale_last_edited=&#8221;on|desktop&#8221; transform_translate=&#8221;-120px|40px&#8221; transform_translate_tablet=&#8221;0px|0px&#8221; transform_translate_phone=&#8221;&#8221; transform_translate_last_edited=&#8221;on|phone&#8221; transform_translate_linked=&#8221;off&#8221; transform_rotate_tablet=&#8221;&#8221; transform_rotate_phone=&#8221;&#8221; transform_rotate_last_edited=&#8221;on|desktop&#8221; transform_skew_tablet=&#8221;&#8221; transform_skew_phone=&#8221;&#8221; transform_skew_last_edited=&#8221;on|desktop&#8221; transform_origin_tablet=&#8221;&#8221; transform_origin_phone=&#8221;&#8221; transform_origin_last_edited=&#8221;on|desktop&#8221; transform_styles_last_edited=&#8221;on|phone&#8221; text_orientation=&#8221;left&#8221; background_layout=&#8221;light&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;|-40px||80px|false|false&#8221; custom_margin_tablet=&#8221;||-60px|&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; custom_padding=&#8221;|1px|25px||false|false&#8221; link_option_url=&#8221;https:\/\/k-ny.art\/it\/ibiza-sound\/&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; transform_styles_tablet=&#8221;&#8221; transform_styles_phone=&#8221;&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; box_shadow_style_button=&#8221;preset2&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;1px&#8221; box_shadow_blur_button=&#8221;0px&#8221; box_shadow_color_button=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>ARTWORK<\/p>\n<h2>IBIZA SOUND<\/h2>\n<p>&nbsp;<\/p>\n<p><strong>Feel it. Live it. <\/strong><strong>ARTWORK<\/strong><\/p>\n<p>Parte del Cluster VIBES &#038; FLOW (Opera n. 1 di 5).<br \/>Tecnica: acrilico, inchiostro fotoluminescente, collage e tecnica mixed-media 3D su tela. Texture artigianali realizzate con la INK3D Rebel Technique. <\/p>\n<p>Caratteristiche speciali: composizione dual-spectrum \u2014 trasformazione visibile tra giorno e notte; elementi luminosi attivati nell\u2019oscurit\u00e0.<\/p>\n<p>IBIZA SOUND esplora il ritmo come atmosfera, vibrazione e movimento emotivo. L\u2019opera non rappresenta Ibiza come luogo geografico, ma come frequenza percettiva modellata da luce, acqua, musica, calore, apertura ed energia collettiva. <\/p>\n<p>Campi cromatici stratificati, attivazioni luminose e texture scultoree creano un ritmo visivo mutevole tra calma e intensit\u00e0, movimento e sospensione. Di giorno, la composizione irradia calore, movimento e profondit\u00e0 spaziale. Di notte emerge una seconda realt\u00e0 \u2014 strutture luminose si attivano sotto la superficie trasformando l\u2019opera in un flusso vivo di energia e sensazione.  <\/p>\n<p>All\u2019interno del sistema K-NY, IBIZA SOUND rappresenta lo stato di impulso di VIBES &#038; FLOW \u2014 la prima immersione nel ritmo, nell\u2019apertura emotiva e nella libert\u00e0 percettiva.<\/p>\n<p>L\u2019opera cattura una condizione che non pu\u00f2 essere posseduta materialmente, ma solo vissuta emotivamente \u2014 il momento in cui il tempo si dissolve, la percezione si ammorbidisce e l\u2019energia diventa presenza.<\/p>\n<p>Originale, pezzo unico.<br \/>Firmato, certificato e disponibile su richiesta.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2025\/11\/K-NY-THINK-BIG-\u2013-REBEL-T.jpg&#8221; title_text=&#8221;Screenshot&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; parallax=&#8221;on&#8221; width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_cta _builder_version=&#8221;4.27.6&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_bg_color_gradient_stops=&#8221;#ffffff 90%|#000000 100%&#8221; button_bg_color_gradient_start=&#8221;#ffffff&#8221; button_bg_color_gradient_start_position=&#8221;90%&#8221; button_bg_color_gradient_end=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; button_custom_padding=&#8221;|0px||0px||true&#8221; transform_scale_tablet=&#8221;&#8221; transform_scale_phone=&#8221;&#8221; transform_scale_last_edited=&#8221;on|desktop&#8221; transform_translate=&#8221;-120px|40px&#8221; transform_translate_tablet=&#8221;0px|0px&#8221; transform_translate_phone=&#8221;&#8221; transform_translate_last_edited=&#8221;on|phone&#8221; transform_translate_linked=&#8221;off&#8221; transform_rotate_tablet=&#8221;&#8221; transform_rotate_phone=&#8221;&#8221; transform_rotate_last_edited=&#8221;on|desktop&#8221; transform_skew_tablet=&#8221;&#8221; transform_skew_phone=&#8221;&#8221; transform_skew_last_edited=&#8221;on|desktop&#8221; transform_origin_tablet=&#8221;&#8221; transform_origin_phone=&#8221;&#8221; transform_origin_last_edited=&#8221;on|desktop&#8221; transform_styles_last_edited=&#8221;on|phone&#8221; text_orientation=&#8221;left&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;|-41px||80px|false|false&#8221; custom_margin_tablet=&#8221;||-60px|&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; custom_padding=&#8221;||25px||false|false&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; transform_styles_tablet=&#8221;&#8221; transform_styles_phone=&#8221;&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; box_shadow_style_button=&#8221;preset2&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;1px&#8221; box_shadow_blur_button=&#8221;0px&#8221; box_shadow_color_button=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span style=\"color: #dfb758;\">ORIGINALI NASCOSTI<\/span><\/h3>\n<p><span style=\"color: #ffcc00;\"><\/span><\/p>\n<p>\nOltre la collezione pubblica esiste uno strato pi\u00f9 silenzioso del sistema K-NY \u2014 uno spazio in cui le opere rimangono intenzionalmente non pubblicate, preservate per collezionisti che comprendono la rarit\u00e0 come forma di precisione culturale.\n<\/p>\n<p>\nI Private Releases e la Vaulted Collection rivelano opere che rimangono fuori dalla visibilit\u00e0 pubblica: originali custoditi nella discrezione e rilasciati esclusivamente attraverso un dialogo personale.\n<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;11px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/k-ny.art\/it\/the-vault\/&#8221; button_text=&#8221;Entra nel Vault&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; button_text_color=&#8221;#DFB758&#8243; button_bg_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_color=&#8221;#DFB758&#8243; button_font=&#8221;&#8211;et_global_heading_font||||||||&#8221; button_use_icon=&#8221;off&#8221; animation_style=&#8221;slide&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;20px|||||&#8221; custom_padding=&#8221;25px||13px|||&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>AUTHENTICITY &#038; ARCHIVING<\/h4>\n<p>Ogni opera \u00e8 un pezzo unico e parte di un Cluster \u2014 una serie chiusa di cinque opere.<\/p>\n<p>Tutte le opere sono state firmate personalmente, numerate e assegnate a un codice ufficiale K-NY da Ki\u00e9ra Nagy (K-NY).<\/p>\n<p>Ogni opera \u00e8 registrata all\u2019interno dell\u2019Archivio K-NY ed \u00e8 accompagnata da un Certificato di Autenticit\u00e0.<\/p>\n<p>Non esistono riproduzioni n\u00e9 edizioni.<\/p>\n<p>K-NY non produce \u2014 pubblica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;14px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4 style=\"text-align: left;\">Night Colors. Illumination in the Dark. <b><\/b><\/h4>\n<p>K-NY non scompare nella notte.<br \/>Si trasforma.<\/p>\n<p>Quando la luce svanisce, un altro livello dell\u2019opera inizia a emergere.<br \/>Caricati dalla luce del giorno, dalla luce artificiale o dalla luce nera, gli elementi fotoluminescenti attivano la superficie e spostano la percezione dell\u2019opera.<\/p>\n<p>Ci\u00f2 che di giorno appare controllato e silenzioso pu\u00f2 diventare luminoso, instabile o psicologicamente carico nell\u2019oscurit\u00e0.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">L\u2019opera non esiste pi\u00f9 come immagine fissa.<br \/>Inizia a operare attraverso trasformazione, memoria e percezione.<\/p>\n<p>La luce non viene utilizzata come effetto.<br \/>Funziona come struttura, attivazione e linguaggio.<\/p>\n<p>La notte non ripete l\u2019opera.<br \/>Rivela un altro stato di essa..[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.27.4&#8243; max_width=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/k-ny.art\/wp-content\/uploads\/2026\/04\/K-NY-Artwork-ZERO-IN-scaled.jpeg&#8221; alt=&#8221;K-NY artwork ZERO IN \u2013 focused luminous acrylic art from the FOCUS &amp; STRENGTH cluster&#8221; title_text=&#8221;K-NY Artwork ZERO IN&#8221; url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; _builder_version=&#8221;4.27.6&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;custom&#8221; background_image_width=&#8221;40%&#8221; background_position=&#8221;bottom_left&#8221; max_width=&#8221;800px&#8221; max_width_tablet=&#8221;560px&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;||&#8221; custom_padding=&#8221;||40px|78px||&#8221; custom_padding_tablet=&#8221;40px|30px|0px|0px&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|desktop&#8221; background_position_tablet=&#8221;top_right&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.2)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.4&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_cta title=&#8221;Opere disponibili&#8221; button_url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; button_text=&#8221;Non per tutti \u2014 scopri perch\u00e9.&#8221; _builder_version=&#8221;4.27.6&#8243; header_level=&#8221;h3&#8243; header_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; header_font_size=&#8221;18px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;||||||||&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_bg_color_gradient_stops=&#8221;#ffffff 90%|#000000 100%&#8221; button_bg_color_gradient_start=&#8221;#ffffff&#8221; button_bg_color_gradient_start_position=&#8221;90%&#8221; button_bg_color_gradient_end=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_border_radius=&#8221;0px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|&#8211;et_global_heading_font_weight|||||||&#8221; button_custom_padding=&#8221;|0px||0px||true&#8221; transform_scale_tablet=&#8221;&#8221; transform_scale_phone=&#8221;&#8221; transform_scale_last_edited=&#8221;on|desktop&#8221; transform_translate=&#8221;-120px|40px&#8221; transform_translate_tablet=&#8221;0px|0px&#8221; transform_translate_phone=&#8221;&#8221; transform_translate_last_edited=&#8221;on|phone&#8221; transform_translate_linked=&#8221;off&#8221; transform_rotate_tablet=&#8221;&#8221; transform_rotate_phone=&#8221;&#8221; transform_rotate_last_edited=&#8221;on|desktop&#8221; transform_skew_tablet=&#8221;&#8221; transform_skew_phone=&#8221;&#8221; transform_skew_last_edited=&#8221;on|desktop&#8221; transform_origin_tablet=&#8221;&#8221; transform_origin_phone=&#8221;&#8221; transform_origin_last_edited=&#8221;on|desktop&#8221; transform_styles_last_edited=&#8221;on|phone&#8221; text_orientation=&#8221;left&#8221; background_layout=&#8221;light&#8221; custom_margin_tablet=&#8221;||-60px|&#8221; custom_margin_last_edited=&#8221;off|tablet&#8221; link_option_url=&#8221;https:\/\/k-ny.art\/it\/opere\/&#8221; header_font_size_last_edited=&#8221;off|desktop&#8221; transform_styles_tablet=&#8221;&#8221; transform_styles_phone=&#8221;&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; box_shadow_style_button=&#8221;preset2&#8243; box_shadow_horizontal_button=&#8221;0px&#8221; box_shadow_vertical_button=&#8221;1px&#8221; box_shadow_blur_button=&#8221;0px&#8221; box_shadow_color_button=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Selezionate.<br \/>Mai ripetute.<\/p>\n<p>Ogni opera \u00e8 una dichiarazione autonoma: fisica, luminosa, assoluta.<\/p>\n<p>La percezione apre spazi emotivi.<\/p>\n<p>Non si sceglie un K-NY.<br \/>\u00c8 lui a scegliere te.<\/p>\n<p>[\/et_pb_cta][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat-y&#8221; min_height=&#8221;554.4px&#8221; custom_margin=&#8221;||29px|||&#8221; custom_padding=&#8221;0px|||||&#8221; global_module=&#8221;697&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]In K-NY, l\u2019irritazione non \u00e8 mai un incidente.<br \/>Segna il momento in cui il pensiero rifiuta l\u2019obbedienza.<\/p>\n<p>K-NY rappresenta lusso con intelligenza.<br \/>E un cenno luminoso.[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>COLLECTOR POSITIONING (2026)<br \/>K-NY definisce il valore attraverso rarit\u00e0, percezione e rilevanza sistemica.<br \/>Ogni opera \u00e8 unica, firmata, certificata e posizionata all\u2019interno di un\u2019architettura di cluster chiusa.<br \/>Le opere pubblicate formano il livello visibile del sistema.<br \/>Altre esistono esclusivamente come Private Release, Vaulted Work o assenza controllata.<br \/>Prezzo su richiesta.<br \/>K-NY non produce \u2014 pubblica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_menu menu_style=&#8221;centered&#8221; disabled_on=&#8221;off|off|on&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_menu][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.27.4&#8243; border_width_top=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Copyright<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label<br \/>Tutti i diritti riservati.<br \/>Tutte le opere e i contenuti di questo sito web \u2014 incluse immagini, testi e layout \u2014 sono protetti da diritto d\u2019autore. Qualsiasi riproduzione, distribuzione o modifica senza previo consenso scritto dell\u2019artista \u00e8 vietata. <\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_font_size=&#8221;20px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">K-NY <\/span><span style=\"color: #808080;\">PARLA DIRETTAMENTE.<\/span><\/strong><\/p>\n<p>Nessun intermediario. Nessun filtro.<br \/>Se un\u2019opera ha catturato la tua attenzione,<br \/>d\u00ec quale \u2014 e perch\u00e9.<br \/>Il dialogo inizia solo<br \/>quando l\u2019intenzione \u00e8 chiara. <\/p>\n<h3><b><\/b><\/h3>\n<p><strong><span style=\"color: #808080;\">STUDIO (Europe)<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/k-ny.art\/it\/contatti\/\">Visita la pagina Contatti <span>\u2192<\/span><\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">INDIRIZZO<\/span><\/strong><\/p>\n<p>K-NY Studio \u2013 Ufficio<br \/>Ki\u00e9ra Nagy<br \/>Koendgenstr. 3<br \/>45131 Essen, Germania<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><\/span><\/strong><\/p>\n<p><strong><span style=\"color: #808080;\"><br \/>ORARI DI APERTURA<\/span><\/strong><\/p>\n<p>Visite in studio solo su appuntamento..<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">INFORMAZIONI<\/span><\/strong><\/p>\n<p>I prezzi non includono IVA, spedizione e assicurazione.<br \/>Le opere originali di Ki\u00e9ra Nagy (K-NY) sono soggette all\u2019aliquota IVA ridotta del 7 % secondo la normativa fiscale tedesca (\u00a7 12 Abs. 2 Nr. 1 UStG e Allegato 2).<br \/>Per le esportazioni al di fuori dell\u2019UE l\u2019IVA non si applica.<br \/>\u00a9 Ki\u00e9ra Nagy \/ K-NY Art Label \u2014<br \/>Tutti i diritti riservati.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong><span style=\"color: #808080;\">FOLOW<\/span><\/strong><\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.27.6&#8243; custom_margin=&#8221;-20px|||-10px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-20px||&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; filter_invert=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; icon_color__hover=&#8221;#e02b20&#8243;][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/kny.luxuryart\/&#8221; _builder_version=&#8221;4.27.5&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/kny.luxuryart\/&#8221; _builder_version=&#8221;4.27.6&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;http:\/\/www.linkedin.com\/in\/kiera-nagy&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_text disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Iscriviti<\/h3>\n<p>alla newsletter e sii tra i primi a scoprire nuove opere, mostre e contenuti esclusivi in anteprima.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=&#8221;SlavaET|11a914d1cc&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; form_field_background_color=&#8221;#f3f3f4&#8243; form_field_custom_padding=&#8221;12px||12px||true&#8221; header_font=&#8221;Montserrat|||on|||||&#8221; header_font_size=&#8221;14px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.8em&#8221; form_field_font=&#8221;||||||||&#8221; form_field_font_size=&#8221;14px&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; button_custom_padding=&#8221;12px||12px||true&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;-39px||&#8221; border_radii_fields=&#8221;on|0px|0px|0px|0px&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_signup][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>Le opere K-NY sono pubblicate in sistemi chiusi e collocate in collezioni private e istituzionali.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cluster VIBES &#038; FLOW &nbsp; VIBES &#038; FLOW \u2013 Not just rhythm. Flow as a way of life.L&#8217;energia diventa atmosfera.Il movimento diventa libert\u00e0. VIBES &#038; FLOW \u00e8 un cluster chiuso composto da cinque opere.All&#8217;interno del sistema K-NY esplora la relazione tra percezione, tempo e ritmo. Impulso \u2192 Espansione \u2192 Consapevolezza \u2192 Soglia \u2192 Stato Il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-15750","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIBES &amp; FLOW \u2014 Cluster \/ K-NY<\/title>\n<meta name=\"description\" content=\"VIBES &amp; FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIBES &amp; FLOW \u2014 Cluster \/ K-NY\" \/>\n<meta property=\"og:description\" content=\"VIBES &amp; FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/\" \/>\n<meta property=\"og:site_name\" content=\"k-ny.art\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-05T09:48:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/cluster-vibes-flow\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/it\\\/cluster-vibes-flow\\\/\",\"name\":\"VIBES & FLOW \u2014 Cluster \\\/ K-NY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\"},\"datePublished\":\"2025-09-17T15:15:35+00:00\",\"dateModified\":\"2026-07-05T09:48:31+00:00\",\"description\":\"VIBES & FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/cluster-vibes-flow\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-ny.art\\\/it\\\/cluster-vibes-flow\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/it\\\/cluster-vibes-flow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/k-ny.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cluster-VIBES-FLOW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#website\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"name\":\"k-ny.art\",\"description\":\"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-ny.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#organization\",\"name\":\"k-ny.art\",\"url\":\"https:\\\/\\\/k-ny.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"contentUrl\":\"https:\\\/\\\/k-ny.art\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/K-NY-Logo-SW.png\",\"width\":2346,\"height\":1644,\"caption\":\"k-ny.art\"},\"image\":{\"@id\":\"https:\\\/\\\/k-ny.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIBES & FLOW \u2014 Cluster \/ K-NY","description":"VIBES & FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/","og_locale":"it_IT","og_type":"article","og_title":"VIBES & FLOW \u2014 Cluster \/ K-NY","og_description":"VIBES & FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.","og_url":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/","og_site_name":"k-ny.art","article_modified_time":"2026-07-05T09:48:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"27 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/","url":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/","name":"VIBES & FLOW \u2014 Cluster \/ K-NY","isPartOf":{"@id":"https:\/\/k-ny.art\/#website"},"datePublished":"2025-09-17T15:15:35+00:00","dateModified":"2026-07-05T09:48:31+00:00","description":"VIBES & FLOW \u2014 a closed cluster of five works where rhythm becomes structure and resonance becomes spatial continuity. Light as movement within the K-NY system.","breadcrumb":{"@id":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-ny.art\/it\/cluster-vibes-flow\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-ny.art\/it\/cluster-vibes-flow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/k-ny.art\/"},{"@type":"ListItem","position":2,"name":"Cluster-VIBES-FLOW"}]},{"@type":"WebSite","@id":"https:\/\/k-ny.art\/#website","url":"https:\/\/k-ny.art\/","name":"k-ny.art","description":"K-NY.Art \u2013 Urban Luxury Art in Rebellion. Precision in Light.","publisher":{"@id":"https:\/\/k-ny.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-ny.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/k-ny.art\/#organization","name":"k-ny.art","url":"https:\/\/k-ny.art\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/","url":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","contentUrl":"https:\/\/k-ny.art\/wp-content\/uploads\/2025\/07\/K-NY-Logo-SW.png","width":2346,"height":1644,"caption":"k-ny.art"},"image":{"@id":"https:\/\/k-ny.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/comments?post=15750"}],"version-history":[{"count":69,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15750\/revisions"}],"predecessor-version":[{"id":41037,"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/pages\/15750\/revisions\/41037"}],"wp:attachment":[{"href":"https:\/\/k-ny.art\/it\/wp-json\/wp\/v2\/media?parent=15750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}